{"id":2373,"date":"2013-11-29T08:20:24","date_gmt":"2013-11-29T07:20:24","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2373"},"modified":"2013-11-29T08:20:24","modified_gmt":"2013-11-29T07:20:24","slug":"algunos-sonidos-de-diciembre-3","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/11\/29\/algunos-sonidos-de-diciembre-3\/","title":{"rendered":"Algunos sonidos de diciembre"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/11\/29\/algunos-sonidos-de-diciembre-3\/loza\/\" rel=\"attachment wp-att-2374\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2374\" title=\"Loza, bater\u00eda de Los Coronas\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Loza.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Loza.jpg 500w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Loza-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Loza-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El monstruo de la Navidad siempre espanta a los conciertos de rock. La agenda de diciembre suele ser una cosa triste, desangelada, des\u00e9rtica, y este a\u00f1o me parece particularmente vac\u00eda. He seleccionado cuatro conciertos en cuatro salas distintas, todos ellos en la primera quincena: ten\u00eda cinco, que siempre queda m\u00e1s bonito, pero los SubTraBelios (ese h\u00edbrido un poco raro entre Decibelios, La Trapera y Subterranean Kids) han acabado suspendiendo su bolo en Sonora.<\/p>\n<p><strong>Helena Espvall y Rita Braga (d\u00eda 3, Karpinteria Histeria Kolektiboa).<\/strong> Forma parte del programa del <a href=\"http:\/\/www.musicaexmachina.com\/\" target=\"_blank\" rel=\"external nofollow\">MEM<\/a> y es la cita que m\u00e1s me emociona, aunque supongo que a las ocho de la tarde de un martes no podr\u00e9 asistir. <a href=\"http:\/\/www.youtube.com\/watch?v=DK2OZnF5anI\" target=\"_blank\" rel=\"external nofollow\">Rita Braga<\/a> es la reina portuguesa del ukelele, pero a quien sigo desde hace a\u00f1os es a la chelista, guitarrista y vocalista sueco-estadounidense Helena Espvall, miembro de los <a href=\"http:\/\/www.youtube.com\/watch?v=ckwrJkMGzIk\" target=\"_blank\" rel=\"external nofollow\">Espers<\/a> y participante en mil colaboraciones. Ah, el colectivo de marras est\u00e1 en la calle Cortes, n\u00famero 29, 4\u00ba piso, y la entrada es gratis.<\/p>\n<p><strong>Ginger Baker Jazz Confusion (d\u00eda 4, Sala BBK).<\/strong> Ya saben que Ginger Baker es una leyenda del rock, en su calidad de bater\u00eda de Cream y Blind Faith, pero aqu\u00ed viene como <a href=\"http:\/\/www.youtube.com\/watch?v=fz_JCMgIK_A\" target=\"_blank\" rel=\"external nofollow\">artista de jazz<\/a>, que dicen que siempre fue su aut\u00e9ntica vocaci\u00f3n. En el cuarteto figura el saxofonista Pee Wee Ellis, colaborador de James Brown que en los \u00faltimos a\u00f1os se ha mudado a Gran Breta\u00f1a. Si tienen un rato y leen ingl\u00e9s, echen un vistazo a <a href=\"http:\/\/www.rollingstone.com\/music\/news\/q-a-ginger-baker-on-why-the-rolling-stones-are-not-good-musicians-20131011\" target=\"_blank\" rel=\"external nofollow\">esta amena entrevista<\/a> del mes pasado con Ginger Baker, desesperante y cortante: \u00abNo me acercar\u00eda a diez millas de un concierto de los Rolling Stones\u00bb, dice.<\/p>\n<p><strong>Los Coronas (d\u00eda 6, Kafe Antzokia).<\/strong> No s\u00e9 si alguien llevar\u00e1 la cuenta de las veces que Los Coronas han venido por aqu\u00ed en los \u00faltimos a\u00f1os, pero sus directos siempre merecen la pena: la m\u00e1quina propulsada por el bater\u00eda Loza, a quien tienen en la foto de arriba, no falla jam\u00e1s. Adem\u00e1s, su \u00faltimo EP, con versiones que van de <a href=\"http:\/\/www.youtube.com\/watch?v=jJ8dh7jR_S8\" target=\"_blank\" rel=\"external nofollow\"><em>Coraz\u00f3n contento<\/em><\/a> a <em>Paint It Black<\/em> y colaboraciones vocales de <a href=\"https:\/\/www.youtube.com\/watch?v=f6xW6KgqtOk\" target=\"_blank\" rel=\"external nofollow\">Eilen Jewell<\/a> y Jairo Zavala, es un artefacto la mar de entretenido.<\/p>\n<p><strong>Chico y Chica (d\u00eda 13, Alh\u00f3ndiga).<\/strong> Estos son directamente de aqu\u00ed, pero a lo mejor han tocado en Bilbao menos que Los Coronas. El d\u00fao tecnopop, siempre capaz de polarizar a la afici\u00f3n con ese sentido del humor suyo, participa en el ciclo M\u00fasica bajo el agua. La web de la Alh\u00f3ndiga <a href=\"http:\/\/www.alhondigabilbao.com\/detalle-evento\/-\/journal_content\/56_INSTANCE_aJV5\/10140\/3132943\" target=\"_blank\" rel=\"external nofollow\">nos aclara<\/a> que no son necesarios conocimientos previos para asistir a su concierto (cosas de las plantillas), as\u00ed que no hace falta que se empollen la <a href=\"http:\/\/www.chicoychica.com\/4enalicante\/index.php\/Arcoiris\" target=\"_blank\" rel=\"external nofollow\">edici\u00f3n completa<\/a> de su serial <em>4 en Alicante<\/em>.<\/p>\n<p>Ahora, d\u00e9jense llevar cinco minutitos por el chelo de Helena Espvall&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/z849DqhvMjI?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; El monstruo de la Navidad siempre espanta a los conciertos de rock. La agenda de diciembre suele ser una cosa triste, desangelada, des\u00e9rtica, y este a\u00f1o me parece particularmente vac\u00eda. He seleccionado cuatro conciertos en cuatro salas distintas, todos ellos en la primera quincena: ten\u00eda cinco, que siempre queda m\u00e1s bonito, pero los SubTraBelios [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,533,602,1147,1263,1782,2300,2517,2714],"class_list":["post-2373","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-chico-y-chica","tag-conciertos","tag-ginger-baker","tag-helena-espvall","tag-los-coronas","tag-pee-wee-ellis","tag-rita-braga","tag-sonidos-de"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2373"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2373\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}