{"id":2357,"date":"2013-11-22T10:24:32","date_gmt":"2013-11-22T09:24:32","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2357"},"modified":"2013-11-22T10:24:32","modified_gmt":"2013-11-22T09:24:32","slug":"recordando-a-josetxo-bicho","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/11\/22\/recordando-a-josetxo-bicho\/","title":{"rendered":"Recordando a Josetxo Bicho"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/11\/22\/recordando-a-josetxo-bicho\/josetxo-ezponda\/\" rel=\"attachment wp-att-2358\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2358\" title=\"Josetxo Ezponda, de Los Bichos, con un guitarrista espont\u00e1neo\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Josetxo-Ezponda.jpg\" alt=\"\" width=\"233\" height=\"407\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Josetxo-Ezponda.jpg 615w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Josetxo-Ezponda-86x150.jpg 86w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Josetxo-Ezponda-172x300.jpg 172w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/11\/Josetxo-Ezponda-587x1024.jpg 587w\" sizes=\"auto, (max-width: 233px) 100vw, 233px\" \/><\/a>La muerte de <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2006\/09\/08\/gloria-al-rey-bicho\/\" target=\"_blank\">Josetxo Ezponda<\/a>, l\u00edder del grupo navarro Los Bichos, dej\u00f3 a sus seguidores con un doloroso sentimiento de orfandad. Todo el mundo se hab\u00eda acostumbrado ya a su silencio de tantos a\u00f1os, pero eso no hizo m\u00e1s f\u00e1cil acostumbrarse a su repentina ausencia. Un buen pu\u00f1ado de esos fans han acabado reuni\u00e9ndose en el <a href=\"https:\/\/www.facebook.com\/groups\/47579107759\/\" target=\"_blank\" rel=\"external nofollow\">grupo de Facebook<\/a> dedicado a Josetxo y su banda, que ya exist\u00eda en vida del m\u00fasico pero ha crecido r\u00e1pidamente a ra\u00edz de su fallecimiento en abril, cuando la desaz\u00f3n por la noticia empuj\u00f3 a muchos a buscar la compa\u00f1\u00eda de esp\u00edritus afines. La comunidad (todo un argumento a favor de la existencia de las redes sociales) ha acabado convirti\u00e9ndose en una celebraci\u00f3n de la vida y la obra del <em>Rey Bicho<\/em>, con participaci\u00f3n de amigos y conocidos que han aportado documentos valios\u00edsimos: grabaciones de sus grupos anteriores (Neon Provos y Tensi\u00f3n), su maqueta en solitario, fotograf\u00edas, muestras de su obra pl\u00e1stica, c\u00f3mics escaneados, hasta dibujos hechos con un Bic de punta fina cuando ten\u00eda 16 a\u00f1itos&#8230;<\/p>\n<p>El grupo no solo tiene esa dimensi\u00f3n retrospectiva, de desenterrar tesoros y recuerdos, sino que tambi\u00e9n ha servido como caldo de cultivo para un proyecto. Cuatro \u00abdisc\u00edpulos musicales y paisanos\u00bb de Josetxo han puesto en marcha una iniciativa de <em>crowdfunding<\/em> para grabar un EP en vinilo con versiones de canciones suyas, que estar\u00e1 acompa\u00f1ado de una casete rosa (el color fetiche del <em>bicho<\/em>) con cuatro <em>bonus tracks<\/em>, todo ello descargable tambi\u00e9n en forma de <em>emepetreses<\/em>. Los implicados en este tributo a \u00abla figura genial y retorcida de uno de los m\u00fasicos m\u00e1s incomprendidos del panorama nacional\u00bb son <a href=\"http:\/\/robertocmeyer.bandcamp.com\" target=\"_blank\" rel=\"external nofollow\">Roberto C. Meyer<\/a> (The Glitter Souls, The Brillantina&#8217;s&#8230;), <a href=\"http:\/\/jaimecristobal.bandcamp.com\" target=\"_blank\" rel=\"external nofollow\">J\u2019aime<\/a> (Souvenir, The Brillantina\u2019s&#8230;), <a href=\"http:\/\/germancarrascosa.bandcamp.com\" target=\"_blank\" rel=\"external nofollow\">Germ\u00e1n Carrascosa<\/a> (Bananas, Los Muebles&#8230;) y Jon Ulecia (Cantina Bizarro, <a href=\"http:\/\/gravelites.bandcamp.com\" target=\"_blank\" rel=\"external nofollow\">Gravelites<\/a>&#8230;), y <a href=\"http:\/\/www.verkami.com\/projects\/7231-ep-de-vinilo-en-homenaje-a-josetxo-ezponda-los-bichos-asi-que-esto-es-el-fin\" target=\"_blank\" rel=\"external nofollow\">este es el lugar<\/a> donde exponen sus prop\u00f3sitos y donde todos los interesados pueden contribuir. Han elegido como t\u00edtulo <em>As\u00ed que esto es el fin<\/em>, primer verso de la canci\u00f3n <a href=\"http:\/\/www.youtube.com\/watch?v=XzB9cBzUSVE\" target=\"_blank\" rel=\"external nofollow\"><em>Un poco m\u00e1s<\/em><\/a>, pero viene al pelo recordar lo que dec\u00eda la letra un poco despu\u00e9s, porque suena a rebeli\u00f3n ante el silencio inmenso y definitivo: \u00abYo quiero m\u00e1s calor, m\u00e1s alma, \u00a1ruido!, \u00a1yo quiero una explosi\u00f3n!\u00bb.<\/p>\n<p>Una de las canciones elegidas para versionar es mi adorada<em> Wishin\u2019 Shift<\/em>. \u00a1Qu\u00e9 buena ocasi\u00f3n para volver a colgarla por aqu\u00ed!<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/bUQ7gVfm3XQ?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La muerte de Josetxo Ezponda, l\u00edder del grupo navarro Los Bichos, dej\u00f3 a sus seguidores con un doloroso sentimiento de orfandad. Todo el mundo se hab\u00eda acostumbrado ya a su silencio de tantos a\u00f1os, pero eso no hizo m\u00e1s f\u00e1cil acostumbrarse a su repentina ausencia. Un buen pu\u00f1ado de esos fans han acabado reuni\u00e9ndose en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[985,1138,1298,1386,1495,1512,1775,2257,2525,3161],"class_list":["post-2357","post","type-post","status-publish","format-standard","hentry","category-musica","tag-facebook","tag-german-carrascosa","tag-homenajes","tag-jaime","tag-jon-ulecia","tag-josetxo-ezponda","tag-los-bichos","tag-pamplona","tag-roberto-c-meyer","tag-versiones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2357"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2357\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}