{"id":233,"date":"2007-07-18T10:23:00","date_gmt":"2007-07-18T09:23:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=233"},"modified":"2007-07-18T10:23:00","modified_gmt":"2007-07-18T09:23:00","slug":"atraccion-planetaria","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/07\/18\/atraccion-planetaria\/","title":{"rendered":"Atracci\u00f3n planetaria"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/evadidos\/files\/J.jpg\" alt=\"\" width=\"240\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>Les voy a contar mi buen prop\u00f3sito <a href=\"http:\/\/canales.elcorreo.com\/especiales\/bilbao.live.festival2006\/galerias\/conciertos-15-julio\/pages\/bilbao-live-conciertos9.htm\" target=\"_blank\" rel=\"external nofollow\">post-BLF<\/a>: voy a ponerme a escuchar a <a href=\"http:\/\/www.losplanetas.es\/\" target=\"_blank\" rel=\"external nofollow\">Los Planetas<\/a> un poco m\u00e1s en serio. Yo creo que mis problemas con este grupo vienen del hecho de que los oyese por primera vez en &#8216;Disco grande&#8217;, programa radiof\u00f3nico que siempre me pareci\u00f3 detestable por su estrechez de miras, de forma que las loas desmesuradas del locutor Julio Ruiz a &#8216;Mi hermana peque\u00f1a&#8217; cubrieron a estos muchachos de un pringue que todav\u00eda me repele un poco. Pero, a lo largo de todos estos a\u00f1os, les he visto en directo un mont\u00f3n de veces -la primera, todav\u00eda con chica al bajo, en una discoteca de Logro\u00f1o- y en cada concierto me han gustado m\u00e1s que en el anterior, aunque fuese contra mi voluntad. Adem\u00e1s, me ocurre algo muy curioso: apenas conozco su discograf\u00eda, pero estoy seguro de que me sentir\u00eda como pez en el agua trasteando con su discoteca, porque al escucharlos siempre tengo la impresi\u00f3n de que les gustan las mismas cosas que a m\u00ed. Lo de Joy Division y New Order no lo pueden disimular, sobre todo en la base de las canciones, por mucho que algunos no lleguen a darse cuenta a causa del ruido superficial, pero no se trata s\u00f3lo de eso: vean las <a href=\"http:\/\/www.aygolive.net\/lista.asp?id=198\" target=\"_blank\" rel=\"external nofollow\">irreprochables recomendaciones<\/a> musicales de Jota para hacer un viaje de ida y vuelta a Saturno. En cierto modo, creo que Los Planetas est\u00e1n m\u00e1s cerca de sus paisanos Lagartija Nick -para m\u00ed, el mejor grupo de Espa\u00f1a desde hace muchos a\u00f1os- que de sus compa\u00f1eros de generaci\u00f3n indie, entre los que se notaba mucha ignorancia sobre la m\u00fasica del pasado remoto, vamos, de cinco a\u00f1os antes.<\/p>\n<p>Por lo dem\u00e1s, el <a href=\"http:\/\/www.youtube.com\/results?search=bilbao%20live&#038;sort=video_date_uploaded\" target=\"_blank\" rel=\"external nofollow\">BLF<\/a> bien, gracias. \u00bfSe lo resumo en unos numerales? A Guns N&#8217;Roses les pondr\u00eda un 6 (buenas canciones, interpretaci\u00f3n correcta, demencial planteamiento de concierto), lo mismo que a Front 242 y Placebo. A Calamaro y a Los Planetas, un 7. Y a Mando Diao, digan lo que digan por ah\u00ed, un 5 pelado. El curro y los estragos de la edad s\u00f3lo me permitieron ver eso. Ah, y una s\u00faplica a la organizaci\u00f3n: cambien de proveedor de kebabs, por favor, que eso era una ofensa a tantos manipuladores honestos del rulo de carne como tenemos ya en Euskadi.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Les voy a contar mi buen prop\u00f3sito post-BLF: voy a ponerme a escuchar a Los Planetas un poco m\u00e1s en serio. Yo creo que mis problemas con este grupo vienen del hecho de que los oyese por primera vez en &#8216;Disco grande&#8217;, programa radiof\u00f3nico que siempre me pareci\u00f3 detestable por su estrechez de miras, de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[331,602,1018,1088,1220,1799,1869,2352],"class_list":["post-233","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao-live-festival","tag-conciertos","tag-festivales","tag-front-242","tag-guns-nroses","tag-los-planetas","tag-mando-diao","tag-placebo"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=233"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/233\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}