{"id":232,"date":"2006-07-17T12:10:17","date_gmt":"2006-07-17T12:10:17","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=232"},"modified":"2006-07-17T12:10:17","modified_gmt":"2006-07-17T12:10:17","slug":"tercer-asalto-y-la-lona","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/07\/17\/tercer-asalto-y-la-lona\/","title":{"rendered":"Tercer asalto y a la lona"},"content":{"rendered":"<p>Molido, no agitado, he alcanzado la tercera y \u00faltima jornada del Bilbao Live Festival, que alargu\u00e9 por prurito profesional hasta las nueve de la ma\u00f1ana para comprobar fehacientemente que a esa hora los DJs cierran el chiringuito. Espero que esta muestra de celo period\u00edstico compense la osad\u00eda del segundo asalto, cuando me puse a hablar de la banda de Axl sin ser fan ni haber seguido su trayectoria. En realidad, s\u00ed que he seguido su trayectoria, al menos desde el desastre del &#8216;Challenger&#8217;, pero no se inquieten: disfrut\u00e9 bastante del concierto, lo que me permitieron los guitarristas, y si en el a\u00f1o noventa hubiera tenido la visi\u00f3n de que los Gansan tocar\u00edan en Bilbao un d\u00eda, habr\u00eda pagado una ronda de champ\u00e1n Krug. Dicho lo cual, el cartel del tercer d\u00eda promet\u00eda variedad y diversi\u00f3n en gradaci\u00f3n para todos los p\u00fablicos, con los &#8216;indies&#8217; calentando para los campistas. Se sali\u00f3 Planetas del horario asignado para cubrir el hueco que dej\u00f3 Tricky, retenido por razones de visado en la frontera estadounidense. Tocaron a medianoche el repertorio que uno hubiera esperado a las siete y media de la tarde, con temas demasiado nuevos para satisfacer a sus fieles, aunque dejaron caer al final un par de himnos. Antes, vimos a unos Pretenders imperecederos y a los eficaces Roth y Calamaro, que movieron a la marea humana con la capacidad de arrastre de la luna. No estuvimos atentos a Placebo (nos dijeron que estuvieron bien) y llegamos justitos a Rinocerose, que suele programarse a las tantas para reanimar al personal con r\u00e1fagas de rock y electr\u00f3nica. Y no est\u00e1 mal pensado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Molido, no agitado, he alcanzado la tercera y \u00faltima jornada del Bilbao Live Festival, que alargu\u00e9 por prurito profesional hasta las nueve de la ma\u00f1ana para comprobar fehacientemente que a esa hora los DJs cierran el chiringuito. Espero que esta muestra de celo period\u00edstico compense la osad\u00eda del segundo asalto, cuando me puse a hablar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[143,331,1799,2975,3093],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-musica","tag-andres-calamaro","tag-bilbao-live-festival","tag-los-planetas","tag-the-pretenders","tag-tricky"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}