{"id":2315,"date":"2013-10-25T08:06:31","date_gmt":"2013-10-25T07:06:31","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2315"},"modified":"2013-10-25T08:06:31","modified_gmt":"2013-10-25T07:06:31","slug":"cancion-de-la-semana-candy-gun","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/10\/25\/cancion-de-la-semana-candy-gun\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Candy Gun&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/10\/25\/cancion-de-la-semana-candy-gun\/melt-banana\/\" rel=\"attachment wp-att-2316\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2316\" title=\"El d\u00fao Melt-Banana (Agata y Yako), de Tokio\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana.jpg\" alt=\"\" width=\"600\" height=\"327\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana.jpg 865w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana-150x82.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana-300x164.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana-768x419.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/10\/Melt-Banana-600x327.jpg 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>No suelo esperar sorpresas de un grupo que lleva dos d\u00e9cadas de carrera, y menos a\u00fan si ese grupo son los japoneses <a href=\"http:\/\/www.geocities.jp\/azaplink\/mb\/mxbx.html\" target=\"_blank\" rel=\"external nofollow\">Melt-Banana<\/a>, de los que no esper\u00e9 sorpresas nunca, m\u00e1s all\u00e1 del tremendo pasmo inicial que produce su sonido. Melt-Banana siempre tuvieron la facultad de destacar en cualquier recopilatorio para los amiguetes, porque sus canciones eran fren\u00e9ticas p\u00edldoras, brev\u00edsimas e hiperactivas, en las que ritmos y riffs se atropellaban por debajo de la voz punzante de la vocalista Yako. A mucha gente le produc\u00edan un rechazo inmediato, visceral. A m\u00ed siempre me gustaron, pero en peque\u00f1as dosis, porque diez minutos de Melt-Banana equival\u00edan a tres \u00e1lbumes completos de otra gente y te dejaban exhausto, con una necesidad f\u00edsica de escuchar canto gregoriano. \u00abAlguna gente dice que son una banda de noise, alguna gente dice que son lo que se llama banda no-wave, alguna gente dice que son una banda hardcore, alguna gente dice que su m\u00fasica es como una monta\u00f1a rusa en un parque de atracciones\u00bb, enumeran en su p\u00e1gina oficial, donde tambi\u00e9n aclaran (y es una puntualizaci\u00f3n muy necesaria) que sus letras son en ingl\u00e9s.<\/p>\n<p>Y aqu\u00ed estoy, alucinando con lo nuevo de Melt-Banana. Me los he reencontrado despu\u00e9s de varios a\u00f1os sin escuchar sus lanzamientos y veo que han conseguido eso tan dif\u00edcil de dar un paso de gigante sin renunciar a sus singulares ingredientes musicales. El \u00e1lbum se titula <em>Fetch<\/em> e incluye doce temas en treinta y dos minutos: para otro grupo a lo mejor eso era un signo de concisi\u00f3n, pero en el caso de Melt-Banana viene a delatar que han hecho un disco progresivo, una tendencia que, seg\u00fan leo, ya iniciaron con el anterior. Han dejado que las canciones crezcan sin las prisas de anta\u00f1o y les ha quedado un surtido variado, intenso y, sobre todo, enormemente disfrutable, que a la vez sigue sonando a ellos y conserva su alma trepidante. <em>Candy Gun<\/em> es el corte que abre el disco, aunque les advierto ya de que, si les ofenden las voces agudas, esto a lo mejor no est\u00e1 hecho para ustedes.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/RgnoBN007Vc?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; No suelo esperar sorpresas de un grupo que lleva dos d\u00e9cadas de carrera, y menos a\u00fan si ese grupo son los japoneses Melt-Banana, de los que no esper\u00e9 sorpresas nunca, m\u00e1s all\u00e1 del tremendo pasmo inicial que produce su sonido. Melt-Banana siempre tuvieron la facultad de destacar en cualquier recopilatorio para los amiguetes, porque [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1417,1945],"class_list":["post-2315","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-japon","tag-melt-banana"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2315"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2315\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}