{"id":2261,"date":"2013-09-05T09:32:41","date_gmt":"2013-09-05T08:32:41","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2261"},"modified":"2013-09-05T09:32:41","modified_gmt":"2013-09-05T08:32:41","slug":"canciones-en-el-horno-8-edificios","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/09\/05\/canciones-en-el-horno-8-edificios\/","title":{"rendered":"Canciones en el horno 8: &#039;Edificios&#039;"},"content":{"rendered":"<p>Ya tiene dos a\u00f1itos este tema de <a href=\"http:\/\/obediencia-punk.blogspot.com.es\/\" target=\"_blank\" rel=\"external nofollow\">Obediencia<\/a>, grupo punk de Madrid con letras en castellano y sonido intenso. Me hab\u00eda preguntado alguna vez si su bautismo ten\u00eda algo que ver con <a href=\"http:\/\/www.youtube.com\/watch?v=lIQb6e-3Jhs\" target=\"_blank\" rel=\"external nofollow\">el viejo tema<\/a> de Gabinete Caligari y compruebo <a href=\"http:\/\/lafonoteca.net\/grupos\/obediencia\" target=\"_blank\" rel=\"external nofollow\">en La Fonoteca<\/a> que s\u00ed, que viene justo de ah\u00ed y que admiran las \u00abgrand\u00edsimas canciones\u00bb que hac\u00edan Jaime Urrutia y compa\u00f1\u00eda en aquella \u00e9poca oscura. Ten\u00eda que decirlo, aunque su estilo no tenga mucho que ver con la referencia. En ese enlace ver\u00e1n tambi\u00e9n que la letra de <em>Edificios<\/em> tiene noble origen literario: \u00abTodo surgi\u00f3 de una frase que me gustaba de un poema de Sylvia Plath. El resto me lo invent\u00e9 un poco mientras ve\u00eda las torres esas de Chamart\u00edn\u00bb, explica la vocalista, Joana. <a href=\"http:\/\/obediencia.bandcamp.com\/\" target=\"_blank\" rel=\"external nofollow\">Aqu\u00ed<\/a>, por cierto, pueden descargarse las cuatro canciones del EP.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0pt none; width: 100%; height: 120px;\" src=\"\/\/bandcamp.com\/EmbeddedPlayer\/album=770653856\/size=medium\/bgcol=ffffff\/linkcol=0687f5\/t=1\/transparent=true\/\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya tiene dos a\u00f1itos este tema de Obediencia, grupo punk de Madrid con letras en castellano y sonido intenso. Me hab\u00eda preguntado alguna vez si su bautismo ten\u00eda algo que ver con el viejo tema de Gabinete Caligari y compruebo en La Fonoteca que s\u00ed, que viene justo de ah\u00ed y que admiran las \u00abgrand\u00edsimas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[463,1106,1847,2197,2434],"class_list":["post-2261","post","type-post","status-publish","format-standard","hentry","category-musica","tag-canciones-en-el-horno","tag-gabinete-caligari","tag-madrid","tag-obediencia","tag-punk"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2261"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2261\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}