{"id":2225,"date":"2013-07-30T15:17:40","date_gmt":"2013-07-30T14:17:40","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2225"},"modified":"2013-07-30T15:17:40","modified_gmt":"2013-07-30T14:17:40","slug":"otro-rock-de-la-carcel","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/07\/30\/otro-rock-de-la-carcel\/","title":{"rendered":"Otro rock de la c\u00e1rcel"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/07\/30\/otro-rock-de-la-carcel\/h-r\/\" rel=\"attachment wp-att-2226\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-2226\" title=\"Paul H.R. Hudson, vocalista de Bad Brains (foto: Lucian Perkins)\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/07\/H.R-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" \/><\/a>Cuando pienso en m\u00fasica grabada en la c\u00e1rcel, me vienen a la cabeza los directos en Folsom y San Quint\u00edn de Johnny Cash o los \u00e1lbumes que Burzum registr\u00f3 entre rejas, esos en los que el black metal dejaba paso a una <a href=\"http:\/\/www.youtube.com\/watch?v=ANfNGF2igVs\" target=\"_blank\" rel=\"external nofollow\">suerte de folk<\/a> con tecladillo ancestral. Pero <a href=\"http:\/\/dangerousminds.net\/comments\/sacred_love_the_bad_brains_song_that_was_recorded_over_the_phone_from_priso\" target=\"_blank\" rel=\"external nofollow\">ayer descubr\u00ed<\/a> que un tema que me entusiasmaba en mi juventud tambi\u00e9n fue grabado parcialmente en la c\u00e1rcel, o mejor dicho <em>desde<\/em> la c\u00e1rcel, y pido perd\u00f3n si ya conocen la an\u00e9cdota: me refiero al <em>Sacred Love<\/em> de <a href=\"http:\/\/badbrains.com\/\" target=\"_blank\" rel=\"external nofollow\">Bad Brains<\/a>, ese grupo estadounidense que llamaba la atenci\u00f3n en la escena hardcore porque sus componentes eran negros y porque intercalaban cortes m\u00e1s furiosos con otros de reggae, con una naturalidad que hac\u00eda que la cosa pareciese l\u00f3gica.<\/p>\n<p>El caso es que el cantante, <a href=\"http:\/\/badbrains.com\/category\/pics_vids\/hr\/\" target=\"_blank\" rel=\"external nofollow\">H.R.<\/a>, a quien tienen en la foto, estaba cumpliendo condena por distribuci\u00f3n de marihuana y no hab\u00eda dejado grabada la pista vocal del tema, uno de esos que demuestran que el punk tambi\u00e9n tiene sentimientos. As\u00ed que, ni cortos ni perezosos, decidieron grabarle a trav\u00e9s de la l\u00ednea telef\u00f3nica: H.R. consigui\u00f3 quedarse solo en la cabina del penal de Laurel Hill, en Virginia, desenrosc\u00f3 el micr\u00f3fono del aparato para evitar acoples y se puso a cantar: \u00abSacred looooove, sacred looooove&#8230;\u00bb. La letra, claro, hace referencia directa a la situaci\u00f3n (\u00abyo estoy aqu\u00ed dentro, t\u00fa est\u00e1s fuera\u00bb, y tambi\u00e9n \u00abvisitas tuyas todos los martes\u00bb) y el resultado me parece fant\u00e1stico. Por cierto, tampoco ten\u00eda ni idea de la existencia de <a href=\"http:\/\/www.keinhassda.de\/a\/home\/p\/index.php\" target=\"_blank\" rel=\"external nofollow\">Kein Hass Da<\/a>, reputado grupo tributo dedicado a versionar los temas de Bad Brains en alem\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/DnswpHvAqLc?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando pienso en m\u00fasica grabada en la c\u00e1rcel, me vienen a la cabeza los directos en Folsom y San Quint\u00edn de Johnny Cash o los \u00e1lbumes que Burzum registr\u00f3 entre rejas, esos en los que el black metal dejaba paso a una suerte de folk con tecladillo ancestral. Pero ayer descubr\u00ed que un tema que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[148,253,441,1486],"class_list":["post-2225","post","type-post","status-publish","format-standard","hentry","category-musica","tag-anecdotas","tag-bad-brains","tag-burzum","tag-johnny-cash"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2225"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2225\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}