{"id":2192,"date":"2013-07-15T15:53:52","date_gmt":"2013-07-15T14:53:52","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=2192"},"modified":"2013-07-15T15:53:52","modified_gmt":"2013-07-15T14:53:52","slug":"verano-en-tinieblas-1-ritos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/07\/15\/verano-en-tinieblas-1-ritos\/","title":{"rendered":"Verano en tinieblas 1: ritos"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/07\/15\/verano-en-tinieblas-1-ritos\/rites\/\" rel=\"attachment wp-att-2193\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-2193\" title=\"Portada de 'Rites', de Paul Jebanasam\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/07\/Rites.jpg\" alt=\"\" width=\"214\" height=\"214\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/07\/Rites.jpg 400w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/07\/Rites-150x150.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/07\/Rites-300x300.jpg 300w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a>Bienvenidos a la nave del misterio. No s\u00e9 si ser\u00e1 casualidad o un modo de protegerme del sol y el bochornazo, pero el caso es que el verano me ha pillado con una provisi\u00f3n m\u00e1s amplia de lo normal de sonidos tenebrosos. Y no me refiero a pop m\u00e1s o menos oscurillo, sino a arquitecturas sonoras m\u00e1s abstractas que aprovechan elementos de la cl\u00e1sica contempor\u00e1nea, la electr\u00f3nica, la new age, la m\u00fasica industrial, eso que llaman <em>drone<\/em> (con sus distintos apellidos, desde metal hasta folk) y dem\u00e1s parentela poco sonriente. Son discos ideales para bajar las persianas y escuchar a buen volumen, como quien se interna en una cueva o en una catedral. As\u00ed que me he dicho&#8230; \u00bfpor qu\u00e9 no proponerlos aqu\u00ed, por si alguien quiere tumbarse a su sombra?<\/p>\n<p>Esta primera entrega se titula <em>Rites<\/em> y es el primer \u00e1lbum firmado por <a href=\"http:\/\/www.subtextrecordings.net\/SUBCD004.html\" target=\"_blank\" rel=\"external nofollow\">Paul Jebanasam<\/a>, un m\u00fasico nacido en Sri Lanka y afincado en Bristol. Jebanasam, capo del sello Subtext, ya hab\u00eda editado dubstep bajo el nombre de Moving Ninja, pero este monstruo que acaba de parir no parece tener mucho encaje en ning\u00fan club de este mundo: ha sobrevivido, eso s\u00ed, su amor por los graves abisales, que ha llevado a alg\u00fan periodista a describir el disco como \u00abplacas tect\u00f3nicas que se funden\u00bb. <em>Rites<\/em> se plantea como una \u00abexploraci\u00f3n de la m\u00fasica lit\u00fargica\u00bb, a trav\u00e9s de cinco movimientos en los que muchos sonidos aparecen desfigurados hasta lo irreconocible, aunque tambi\u00e9n afloran, por ejemplo, pasajes cl\u00e1sicos de viola. Una hermosura. <a href=\"http:\/\/thequietus.com\/articles\/12002-paul-jebanasam-rites-subtext-stream-full-album\" target=\"_blank\" rel=\"external nofollow\">Aqu\u00ed<\/a> pueden escuchar el \u00e1lbum entero, pero les cuelgo el primer movimiento, una especie de p\u00f3rtico m\u00e1s luminoso que lo que viene despu\u00e9s.<\/p>\n<p>&nbsp;<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/19w6NNTpng4?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Bienvenidos a la nave del misterio. No s\u00e9 si ser\u00e1 casualidad o un modo de protegerme del sol y el bochornazo, pero el caso es que el verano me ha pillado con una provisi\u00f3n m\u00e1s amplia de lo normal de sonidos tenebrosos. Y no me refiero a pop m\u00e1s o menos oscurillo, sino a arquitecturas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,2289,2742,3159],"class_list":["post-2192","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-paul-jebanasam","tag-sri-lanka","tag-verano-en-tinieblas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=2192"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/2192\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=2192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=2192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=2192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}