{"id":1978,"date":"2013-02-15T09:10:13","date_gmt":"2013-02-15T08:10:13","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1978"},"modified":"2013-02-15T09:10:13","modified_gmt":"2013-02-15T08:10:13","slug":"cancion-de-la-semana-destructores","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/02\/15\/cancion-de-la-semana-destructores\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Destructores&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2013\/02\/15\/cancion-de-la-semana-destructores\/portada-de-hipermejores\/\" rel=\"attachment wp-att-1979\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1979\" title=\"Portada de Hipermejores, de Comando Suzie\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/02\/Portada-de-Hipermejores.jpg\" alt=\"\" width=\"132\" height=\"119\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/02\/Portada-de-Hipermejores.jpg 400w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2013\/02\/Portada-de-Hipermejores-300x273.jpg 300w\" sizes=\"auto, (max-width: 132px) 100vw, 132px\" \/><\/a>Al <a href=\"http:\/\/archive.org\/details\/ComandoSuzieElHombreSentimental\" target=\"_blank\" rel=\"external nofollow\">disco anterior<\/a> de Comando Suzie llegu\u00e9 un poquito tarde: <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2011\/01\/27\/el-mejor-disco-del-ano-pasado\/\" target=\"_blank\">por unos d\u00edas<\/a> no pude incluirlo entre los mejores de 2010, con lo que me gust\u00f3 entonces y me sigue gustando ahora. As\u00ed que con el nuevo me voy a apresurar, aun a riesgo de pasarme de acelerado, y voy a colocarles como<em> canci\u00f3n de la semana<\/em> el \u00fanico tema que han desvelado hasta ahora. Luego, ay, habr\u00e1 alguna todav\u00eda mejor y ya no podr\u00e9 hacerle hueco aqu\u00ed, por esa regla absurda de no repetir nunca artista en la secci\u00f3n. En realidad, la norma me la he impuesto yo y podr\u00eda derogarla ahora mismo, pero perm\u00edtanme esa satisfacci\u00f3n de mandar en alguien.<\/p>\n<p>El \u00e1lbum completo, titulado <a href=\"http:\/\/us6.campaign-archive2.com\/?u=242c0c87bb2612e984a8ec324&#038;id=bccad96762\" target=\"_blank\" rel=\"external nofollow\"><em>Hipermejores<\/em><\/a>, no saldr\u00e1 hasta el mes que viene, pero ya conocemos este <em>Destructores<\/em>. El protagonista de la letra, el temible <em>Destructor<\/em>, es una figura que por desgracia todos hemos llegado a conocer: el internauta justiciero, ese talib\u00e1n de su propio gusto que se pronuncia con particular agresividad y desd\u00e9n en todo lo vinculado con la m\u00fasica. Aqu\u00ed lo tienen, despotricando sobre unas bonitas bases de pop sint\u00e9tico y con un impetuoso solo final. \u00abEso que dicen que es un <em>hit<\/em> \u2013canta Ra\u00fal L\u00f3pez, el <em>comandante<\/em> del proyecto\u2013 es una mierda que hay que destruir\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><object width=\"100%\" height=\"81\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"https:\/\/player.soundcloud.com\/player.swf?url=http%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F79035687&#038;show_comments=false&#038;auto_play=false&#038;color=ff7700\" \/><embed width=\"100%\" height=\"81\" type=\"application\/x-shockwave-flash\" src=\"https:\/\/player.soundcloud.com\/player.swf?url=http%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F79035687&#038;show_comments=false&#038;auto_play=false&#038;color=ff7700\" allowscriptaccess=\"always\" \/><\/object><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al disco anterior de Comando Suzie llegu\u00e9 un poquito tarde: por unos d\u00edas no pude incluirlo entre los mejores de 2010, con lo que me gust\u00f3 entonces y me sigue gustando ahora. As\u00ed que con el nuevo me voy a apresurar, aun a riesgo de pasarme de acelerado, y voy a colocarles como canci\u00f3n de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,593],"class_list":["post-1978","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-comando-suzie"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1978"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1978\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}