{"id":192,"date":"2006-05-10T10:03:36","date_gmt":"2006-05-10T10:03:36","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=191"},"modified":"2006-05-10T10:03:36","modified_gmt":"2006-05-10T10:03:36","slug":"musica-volverse-loco","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/05\/10\/musica-volverse-loco\/","title":{"rendered":"M\u00fasica para volverse loco"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px\" src=\"\/evadidos\/files\/sco.jpg\" alt=\"\" width=\"200\" height=\"160\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>El mundo del rock est\u00e1 lleno de artistas que van de raros y de oscuros, incluso abundan quienes pretenden dar miedo a base de gritos, ruido, maquillaje o actitudes que ellos suponen propias de un demente. Puede ser divertido seguirles la corriente, jugar un rato a ser malos, pero a casi todos se les ve la pose a poco que se les mire con seriedad: uno se imagina a tipos como <a href=\"http:\/\/cof.rockmetal.art.pl\/images\/galeria\/1.jpg\" target=\"_blank\" rel=\"external nofollow\">Dani Filth<\/a> igual que al punk burgu\u00e9s del anuncio de coches, sorbiendo burdeos mientras les hacen la pedicura francesa con esmalte negro. Tuve un recuerdo para estos impostores la otra noche, cuando empec\u00e9 a escuchar con auriculares el nuevo disco de Scott Walker, <a href=\"http:\/\/www.the-drift.net\/\" target=\"_blank\" rel=\"external nofollow\">&#8216;The Drift&#8217;<\/a>. La mayor parte del \u00e1lbum es, como poco, inquietante, con algunos pasajes que directamente asustan y otros que&#8230; s\u00ed, lo dir\u00e9, dan algo de risa, porque un paso m\u00e1s all\u00e1 de estas experiencias extremas s\u00f3lo queda el humor. Me ha tranquilizado que el propio Walker lo admita: \u00abEl disco es bastante divertido, porque, sin eso, el arte se desequilibra\u00bb, ha comentado a &#8216;The Wire&#8217;. Lo de <em>divertido <\/em>enti\u00e9ndanlo en plan relativo, como un desahogo de tanta angustia, igual que la risa que te puede entrar al darte cuenta de que vas a morir joven y solo en el fondo de un pozo.<\/p>\n<p>Walker es un recluso del rock, una figura similar a las de Pynchon o Salinger en la literatura. Pero lo curioso de nuestro hombre es su pasado: ahora ni siquiera se deja retratar debidamente, pero a mediados de los 60 fue un \u00eddolo de multitudes como cabeza visible de los <a href=\"http:\/\/postpunkjunk.com\/?p=18\" target=\"_blank\" rel=\"external nofollow\">Walker Brothers<\/a>, que ni se apellidaban Walker ni eran <em>brothers<\/em>. Las fans brit\u00e1nicas intentaban desnudarlo, asaltaban sus hoteles, se deshac\u00edan al escuchar himnos melanc\u00f3licos como <a href=\"http:\/\/www.youtube.com\/watch?v=QElVbzCmU44&#038;search=walker%20brothers\" target=\"_blank\" rel=\"external nofollow\">&#8216;The Sun Ain&#8217;t Gonna Shine Anymore&#8217;<\/a>, mientras el inadaptado Scott confesaba al &#8216;Melody Maker&#8217; su sue\u00f1o de conocer alg\u00fan d\u00eda a Jean Paul Sartre. Ese <em>alien <\/em>torturado que lat\u00eda en el interior del vocalista acab\u00f3 adue\u00f1\u00e1ndose de todo su ser en los 90, con el tremebundo <a href=\"http:\/\/obscuresound.com\/?p=50\" target=\"_blank\" rel=\"external nofollow\">&#8216;Tilt&#8217;<\/a>, y sigue domin\u00e1ndolo en &#8216;The Drift&#8217;, un disco de canciones descoyuntadas y marcianas donde se mezclan ominosos arreglos de cuerda, percusiones imprevistas y la voz dram\u00e1tica y excesiva de Walker. El sol, desde luego, sigue brillando poco en su mundo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El mundo del rock est\u00e1 lleno de artistas que van de raros y de oscuros, incluso abundan quienes pretenden dar miedo a base de gritos, ruido, maquillaje o actitudes que ellos suponen propias de un demente. Puede ser divertido seguirles la corriente, jugar un rato a ser malos, pero a casi todos se les ve [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[673,774,2612,2905,3042],"class_list":["post-192","post","type-post","status-publish","format-standard","hentry","category-musica","tag-dani-filth","tag-discos","tag-scott-walker","tag-the-drift","tag-tilt"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}