{"id":1856,"date":"2012-12-04T10:00:02","date_gmt":"2012-12-04T09:00:02","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1856"},"modified":"2012-12-04T10:00:02","modified_gmt":"2012-12-04T09:00:02","slug":"canciones-en-el-horno-3-journey-to-the-center-of-the-mind","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/12\/04\/canciones-en-el-horno-3-journey-to-the-center-of-the-mind\/","title":{"rendered":"Canciones en el horno 3: &#039;Journey To The Center Of The Mind&#039;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Bienvenidos a la inesperada fase sesentera de las canciones en el horno. El amigo azar ha escogido este <em>Journey To The Center Of The Mind<\/em>, el gran cl\u00e1sico que <a href=\"http:\/\/www.chromeoxide.com\/amboy.htm\" target=\"_blank\" rel=\"external nofollow\">The Amboy Dukes<\/a> editaron en 1968. Los <em>duques<\/em> proced\u00edan de Detroit y resulta ineludible destacar el hecho de que su guitarra solista era Ted Nugent: ah\u00ed lo tienen, todo pincho en el v\u00eddeo, antes de descubrir los encantos del taparrabos, la caza con flechas, la destrucci\u00f3n masiva y el <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2006\/05\/31\/guitarras-y-otras-armas-fuego\/\" target=\"_blank\">exterminio de pueblos inocentes<\/a>. Este <em>viaje al centro de la mente<\/em> (que a\u00f1os despu\u00e9s, por cierto, versionar\u00edan <a href=\"http:\/\/www.youtube.com\/watch?v=-w7JrN-Odhs\" target=\"_blank\" rel=\"external nofollow\">los Ramones<\/a>) abre la segunda cara del elep\u00e9 hom\u00f3nimo, que parece obviamente centrada en el consumo de alucin\u00f3genos, aunque Nugent sostiene que jam\u00e1s se enter\u00f3 de esas referencias: \u00abDeja atr\u00e1s tus miedos, ven con nosotros y descubre los placeres de un viaje al centro de la mente\u00bb, dice la letra, y tambi\u00e9n \u00abpero, por favor, date cuenta de que probablemente te sorprender\u00e1s, porque es una tierra desconocida para el hombre donde la fantas\u00eda se vuelve realidad, as\u00ed que, si puedes, por favor, comprende que tal vez no regreses\u00bb. Ted, t\u00edo, \u00bfde qu\u00e9 cre\u00edas que hablaban?<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/UN2VNFpiGWo?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Bienvenidos a la inesperada fase sesentera de las canciones en el horno. El amigo azar ha escogido este Journey To The Center Of The Mind, el gran cl\u00e1sico que The Amboy Dukes editaron en 1968. Los duques proced\u00edan de Detroit y resulta ineludible destacar el hecho de que su guitarra solista era Ted Nugent: [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[742,2424,2842,2866],"class_list":["post-1856","post","type-post","status-publish","format-standard","hentry","category-musica","tag-detroit","tag-psicodelia","tag-ted-nugent","tag-the-amboy-dukes"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}