{"id":183,"date":"2006-04-27T13:59:00","date_gmt":"2006-04-27T13:59:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=182"},"modified":"2006-04-27T13:59:00","modified_gmt":"2006-04-27T13:59:00","slug":"paloma-palmolive-paloma","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/04\/27\/paloma-palmolive-paloma\/","title":{"rendered":"Paloma, Palmolive, Paloma"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" height=\"250\" align=\"right\" hspace=\"5\" vspace=\"5\" \/><img decoding=\"async\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" height=\"250\" align=\"right\" hspace=\"5\" vspace=\"5\" \/><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-now.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1141\" style=\"margin-left: 10px; margin-right: 10px;\" title=\"Paloma McLardy, Palmolive, ex Slits\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-now.gif\" alt=\"\" width=\"154\" height=\"239\" \/><\/a>Paloma McLardy es esta apacible se\u00f1ora de mediana edad que ven en la foto de la izquierda. Naci\u00f3 en Espa\u00f1a, se mud\u00f3 a Inglaterra en su juventud y ahora reside en el <em>estado unido<\/em> de Massachusetts. Adem\u00e1s de su esposo y sus tres hijos, lo m\u00e1s importante en su vida es la iglesia a la que pertenece: es una cristiana devota y dedica la mayor parte de su tiempo libre a participar en las actividades de su parroquia. Incluso, en lo que parece una peque\u00f1a excentricidad, toca la bater\u00eda en un grupillo de m\u00fasica cristiana que ha formado junto a su marido y otros feligreses. Pero Paloma tiene un pasado muy diferente al de los dem\u00e1s fieles: hace treinta y tantos a\u00f1os, la llamaban Palmolive y se encargaba de los tambores en <a href=\"http:\/\/www.punk77.co.uk\/groups\/slits.htm\" target=\"_blank\" rel=\"external nofollow\">The Slits<\/a>, es decir, Las Rajas, uno de los grupos m\u00e1s inquietos del punk brit\u00e1nico, con la peculiaridad de estar formado exclusivamente por chicas. Era, claro, la muchacha que ven abajo a la derecha. El apodo se lo puso Paul Simonon, de los Clash, que supli\u00f3 con ingenio su incapacidad para entender bien su nombre real. En aquellos tiempos, Paloma era novia de un tal Woody, que ha quedado para la posteridad como Joe Strummer, y sol\u00eda alternar con un tal Sid Vicious.<\/p>\n<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-then.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1142\" title=\"Palmolive, de las Slits\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-then.jpg\" alt=\"\" width=\"132\" height=\"211\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-then.jpg 212w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-then-94x150.jpg 94w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Palmo-then-188x300.jpg 188w\" sizes=\"auto, (max-width: 132px) 100vw, 132px\" \/><\/a>El \u00fanico material que grab\u00f3 con las Slits fueron sus dos primeras &#8216;Peel sessions&#8217;. A continuaci\u00f3n abandon\u00f3 el grupo, enfadada con sus compa\u00f1eras porque iban a aparecer semidesnudas y cubiertas de barro en su primer \u00e1lbum, el muy recomendable <a href=\"http:\/\/www.pitchforkmedia.com\/record-reviews\/s\/slits\/cut.shtml\" target=\"_blank\" rel=\"external nofollow\">&#8216;Cut&#8217;<\/a>. Entr\u00f3 en las Raincoats y toc\u00f3 en su primer LP, uno de los discos favoritos de personajes como Kurt Cobain o Thurston Moore, y despu\u00e9s&#8230; desapareci\u00f3 en busca de la verdadera fe: fue recalando en la m\u00edstica hind\u00fa, los movimientos <em>new age<\/em> y, finalmente, los cristianos renacidos. Un desenlace curioso, puesto que en su momento escap\u00f3 de Espa\u00f1a agobiada por la constricci\u00f3n nacionalcat\u00f3lica. \u00abLa excitaci\u00f3n que me gustaba de la m\u00fasica punk y que nunca llegu\u00e9 a encontrar en ella -explica- la experimento ahora sirviendo a Jes\u00fas\u00bb. <a href=\"http:\/\/www.palmolive2day.com\/\" target=\"_blank\" rel=\"external nofollow\">Aqu\u00ed<\/a> tienen su p\u00e1gina y <a href=\"http:\/\/www.nstop.com\/paloma\/index.html\" target=\"_blank\" rel=\"external nofollow\">aqu\u00ed<\/a>, la entrevista de unos fans at\u00f3nitos, a quienes he mangado la foto m\u00e1s reciente.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Paloma McLardy es esta apacible se\u00f1ora de mediana edad que ven en la foto de la izquierda. Naci\u00f3 en Espa\u00f1a, se mud\u00f3 a Inglaterra en su juventud y ahora reside en el estado unido de Massachusetts. Adem\u00e1s de su esposo y sus tres hijos, lo m\u00e1s importante en su vida es la iglesia a la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1468,2255,2434,2497,2988],"class_list":["post-183","post","type-post","status-publish","format-standard","hentry","category-musica","tag-joe-strummer","tag-palmolive","tag-punk","tag-religion","tag-the-slits"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}