{"id":175,"date":"2006-04-18T19:48:00","date_gmt":"2006-04-18T19:48:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=174"},"modified":"2006-04-18T19:48:00","modified_gmt":"2006-04-18T19:48:00","slug":"el-retorno-pajaresteso","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/04\/18\/el-retorno-pajaresteso\/","title":{"rendered":"El retorno de Pajaresteso"},"content":{"rendered":"<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Paj.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-1148\" title=\"Andr\u00e9s Pajares y Fernando Esteso\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Paj.jpg\" alt=\"\" width=\"198\" height=\"246\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Paj.jpg 278w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Paj-121x150.jpg 121w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2006\/04\/Paj-242x300.jpg 242w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a>Seguro que est\u00e1n ustedes sobre ascuas con &#8216;El c\u00f3digo Aparinci&#8217;, el largometraje que reunir\u00e1 a dos pesos pesados de la cinematograf\u00eda espa\u00f1ola, dos titanes de la actuaci\u00f3n, dos t\u00edos para partirse: <a href=\"http:\/\/www.geocities.com\/Hollywood\/Set\/9967\/portada.html\" target=\"_blank\" rel=\"external nofollow\">Andr\u00e9s Pajares y Fernando Esteso<\/a>, Fernando Esteso y Andr\u00e9s Pajares, inolvidables protagonistas de &#8216;Los bingueros&#8217;, &#8216;Yo hice a Roque III&#8217; o &#8216;\u00a1Qu\u00e9 gozada de divorcio!&#8217;. En la <a href=\"http:\/\/www.elcodigoaparinci.com\/\" target=\"_blank\" rel=\"external nofollow\">exasperante web<\/a> de su nuevo film, adem\u00e1s de aprender qui\u00e9n es Asmodeo o qu\u00e9 enfrentaba a templarios y hospitalarios, hallamos un poco m\u00e1s de informaci\u00f3n sobre el proyecto: se trata de un \u00abthriller c\u00f3mico\u00bb centrado en las peripecias de Armand y Leo, un gu\u00eda tur\u00edstico y un ch\u00f3fer de autocar afincados en la costa mediterr\u00e1nea. Las vidas de estos honrados trabajadores, que suponemos centradas en la cultura de chiringuito y el ligoteo de escandinavas, se vuelven del rev\u00e9s con la aparici\u00f3n de un pergamino que desvela el paradero de un tesoro de la Orden del Temple. Y a partir de ah\u00ed, ya saben, risas y misterio a raudales, como en una mezcla de &#8216;El c\u00f3digo Da Vinci&#8217; y &#8216;Los extreme\u00f1os se tocan&#8217;. \u00abA veces, los enigmas y secretos del pasado no deber\u00edan ser desvelados\u00bb, dice el eslogan de la peli. Algunos actores tampoco, porque velados estaban muy bien.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Seguro que est\u00e1n ustedes sobre ascuas con &#8216;El c\u00f3digo Aparinci&#8217;, el largometraje que reunir\u00e1 a dos pesos pesados de la cinematograf\u00eda espa\u00f1ola, dos titanes de la actuaci\u00f3n, dos t\u00edos para partirse: Andr\u00e9s Pajares y Fernando Esteso, Fernando Esteso y Andr\u00e9s Pajares, inolvidables protagonistas de &#8216;Los bingueros&#8217;, &#8216;Yo hice a Roque III&#8217; o &#8216;\u00a1Qu\u00e9 gozada de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6],"tags":[3299,564,866,955,1014],"class_list":["post-175","post","type-post","status-publish","format-standard","hentry","category-inclasificables","category-mundo-freak","tag-andres-pajares","tag-cine","tag-el-codigo-aparinci","tag-estrenos","tag-fernando-esteso"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}