{"id":1723,"date":"2012-07-24T12:52:39","date_gmt":"2012-07-24T11:52:39","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1723"},"modified":"2012-07-24T12:52:39","modified_gmt":"2012-07-24T11:52:39","slug":"julieta-recomienda","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/07\/24\/julieta-recomienda\/","title":{"rendered":"Julieta recomienda"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Purity Ring - Fineshrine\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Xqw4wo8vdY8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>La mexicana Julieta Venegas, que <a href=\"http:\/\/bilbaoenvivo.wordpress.com\/2012\/07\/24\/julieta-venegas-la-mas-femenina\/\" target=\"_blank\" rel=\"external nofollow\">estuvo por Bilbao<\/a> el pasado fin de semana, es uno de esos m\u00fasicos atentos a lo que hacen sus colegas: mantiene la curiosidad, la capacidad de sorpresa y la generosidad de elogiar en p\u00fablico lo que le entusiasma (algo l\u00f3gico, natural, pero no tan com\u00fan cuando se alcanza cierto nivel de fama). Pero, adem\u00e1s, ocurre que esta mujer tiene buen gusto. El otro d\u00eda <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/201207\/19\/julieta-venegas.html\" target=\"_blank\" rel=\"external nofollow\">escrib\u00ed por ah\u00ed<\/a> que tres de sus recomendaciones m\u00e1s recientes han sido los barceloneses Pegasvs, que a m\u00ed <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2012\/05\/25\/cancion-de-la-semana-brillar\/\" target=\"_blank\">ya me encantaban<\/a>; los canadienses Purity Ring, a los que hab\u00eda escuchado con agrado pero sin demasiada atenci\u00f3n, y la brasile\u00f1a Nina Becker, de quien no ten\u00eda noticia, para qu\u00e9 vamos a disimular a estas alturas los inmensos boquetes de nuestro conocimiento.<\/p>\n<p>Pues bien, se da la circunstancia de que tanto Purity Ring como Nina Becker acaban de editar discos nuevos, y los dos son excelentes, as\u00ed que he decidido colaborar con Julieta en su acci\u00f3n promocional: ella pone sus dos millones y medio de seguidores de Twitter y yo, la incontable docena de parientes y amigos que leen este blog. Al d\u00fao canadiense lo sol\u00edan emparentar con eso que se dio en llamar <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2010\/10\/11\/musica-casas-embrujadas\/\" target=\"_blank\"><em>witch house<\/em><\/a>, que ser\u00eda un engendro con nombre rid\u00edculo salido del delirio de alg\u00fan cr\u00edtico pero a m\u00ed me gustaba: ritmos electr\u00f3nicos ralentizados, ambientes et\u00e9reos y ominosos, voces distantes y a menudo tratadas, po\u00e9tica m\u00f3rbida&#8230; El \u00e1lbum, <em>Shrines<\/em>, mantiene esas caracter\u00edsticas que a muchos se les atragantan, lo s\u00e9, pero que crean un efecto hipn\u00f3tico y les quedan como un guante a letras como la del espl\u00e9ndido <em>Fineshrine<\/em> que tienen arriba: \u00abDesl\u00edzate en mi estern\u00f3n y envu\u00e9lvete en mis peque\u00f1as costillas\u00bb, viene a decir Megan James. Y aqu\u00ed abajo les cuelgo <em>Cad\u00ea voc\u00ea<\/em>, el corte que abre <a href=\"http:\/\/gambitobudapeste.tumblr.com\/\" target=\"_blank\" rel=\"external nofollow\"><em>Gambito Budapeste<\/em><\/a>, un disco que la carioca Nina Becker ha grabado en casa junto a su marido Marcelo Callado. En \u00e9l abarcan con \u00e9xito desde sonoridades tradicionales brasile\u00f1as hasta psicodelia, pasando por melod\u00edas c\u00e1ndidas y resplandecientes como esta, que a m\u00ed me hace pensar un poco absurdamente en el <em>After Hours<\/em> de la Velvet. Con mejor voz, vale.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"horto sessions #5_nina becker &amp; marcelo callado_parte 1\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/TLKLRJtOC9k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; La mexicana Julieta Venegas, que estuvo por Bilbao el pasado fin de semana, es uno de esos m\u00fasicos atentos a lo que hacen sus colegas: mantiene la curiosidad, la capacidad de sorpresa y la generosidad de elogiar en p\u00fablico lo que le entusiasma (algo l\u00f3gico, natural, pero no tan com\u00fan cuando se alcanza [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[411,458,774,1537,1894,2152,2436],"class_list":["post-1723","post","type-post","status-publish","format-standard","hentry","category-musica","tag-brasil","tag-canada","tag-discos","tag-julieta-venegas","tag-marcelo-callado","tag-nina-becker","tag-purity-ring"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1723"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1723\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}