{"id":172,"date":"2006-04-13T12:01:16","date_gmt":"2006-04-13T12:01:16","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=171"},"modified":"2006-04-13T12:01:16","modified_gmt":"2006-04-13T12:01:16","slug":"beatles-psicofonicos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/04\/13\/beatles-psicofonicos\/","title":{"rendered":"Beatles psicof\u00f3nicos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"The Beatles\" src=\"\/evadidos\/files\/Beatl.jpg\" alt=\"\" width=\"270\" height=\"203\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>Los Beatles son, sin duda, el grupo que m\u00e1s produce pese a tener a la mitad de sus componentes muertos. Y no hablo de recopilaciones, aunque la All Music Guide registra <a href=\"http:\/\/www.allmusic.com\/cg\/amg.dll?p=amg&#038;token=ADFEAEE4781EDC4BA87220C59C3B45CFA176E008FE4BF59A1321435992B63E45915923B70DA1DCCBB0B671AB78ACE02CA45A099FCFE455F9D6663D2DFC93&#038;uid=MIW030604130529&#038;sql=11:2gjiear04xf7%7ET21\" target=\"_blank\" rel=\"external nofollow\">m\u00e1s de setenta<\/a> posteriores a &#8216;Let It Be&#8217;, sino de \u00e1lbumes de &#8220;material completamente nuevo&#8221; como <a href=\"http:\/\/news.bbc.co.uk\/1\/hi\/entertainment\/4905630.stm\" target=\"_blank\" rel=\"external nofollow\">el que est\u00e1 preparando<\/a> la Apple. Esta vez, las canciones in\u00e9ditas no proceden del saco de un chamarilero afortunado, ni del fondo de un caj\u00f3n de la c\u00f3moda de John Lennon, sino, al parecer, de los fecundos archivos oficiales de la compa\u00f1\u00eda. El propio Sir George Martin est\u00e1 remasterizando las grabaciones con la supervisi\u00f3n de McCartney y Starr y la l\u00f3gica aprobaci\u00f3n de los herederos de Lennon y Harrison. Lo que salga de ah\u00ed servir\u00e1 de fondo musical para un espect\u00e1culo del Cirque du Soleil que se estrenar\u00e1 este verano en Las Vegas, capital mundial del buen gusto y la sofisticaci\u00f3n est\u00e9tica, pero tambi\u00e9n dar\u00e1 contenido a un nuevo disco de la banda: &#8220;El p\u00fablico se sentir\u00e1 como si estuviera en la misma habitaci\u00f3n que el grupo&#8221;, ha descrito el hijo de Sir Martin, Giles, tambi\u00e9n muy ilusionado con la perspectiva. Seguro que a todos se les ponen ojos de d\u00f3lar, como a T\u00edo Gilito.<\/p>\n<p>No ser\u00e9 yo quien se meta con una iniciativa que proporciona felicidad a tant\u00edsima gente, pero no me negar\u00e1n que estas exhumaciones de canciones in\u00e9ditas -es decir, desechadas en su momento- van bajando la calidad media de la producci\u00f3n de un artista. Con los \u00e1lbumes <em>oficiales <\/em>de los Beatles, el promedio podr\u00eda ser de 9 (vale, vale, p\u00f3nganles un 10 si quieren), pero cada canci\u00f3n nueva baja la nota unas d\u00e9cimas y a este paso van a acabar con el notable raspado. \u00a1A ver si, por culpa de esta decadencia post-mortem, dejan de ser el mejor grupo de la historia!<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los Beatles son, sin duda, el grupo que m\u00e1s produce pese a tener a la mitad de sus componentes muertos. Y no hablo de recopilaciones, aunque la All Music Guide registra m\u00e1s de setenta posteriores a &#8216;Let It Be&#8217;, sino de \u00e1lbumes de &#8220;material completamente nuevo&#8221; como el que est\u00e1 preparando la Apple. Esta vez, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[188,568,1133,3295],"class_list":["post-172","post","type-post","status-publish","format-standard","hentry","category-musica","tag-apple","tag-cirque-du-soleil","tag-george-martin","tag-the-beatles"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}