{"id":170,"date":"2006-04-11T21:07:11","date_gmt":"2006-04-11T21:07:11","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=169"},"modified":"2006-04-11T21:07:11","modified_gmt":"2006-04-11T21:07:11","slug":"el-codigo-keeler","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2006\/04\/11\/el-codigo-keeler\/","title":{"rendered":"El c\u00f3digo Keeler"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"margin: 5px;\" title=\"Portada de Harry Stephen Keeler\" src=\"\/evadidos\/files\/kee.jpg\" alt=\"\" width=\"200\" height=\"286\" align=\"right\" hspace=\"5\" vspace=\"5\" \/>El <a href=\"http:\/\/blogs.elcorreo.com\/index.php\/evadidos\/2006\/04\/08\/\" target=\"_blank\">post de Arrieta<\/a> sobre el generador de argumentos de Dan Brown me ha reafirmado en la idea de que, si este hombre no hubiese triunfado, alg\u00fan d\u00eda lo reivindicar\u00edan como un ap\u00f3stol de la novela de serie B, como una especie de Ed Wood del thriller literario. S\u00e9 que la siguiente frase puede acarrearme el descr\u00e9dito de por vida y la excomuni\u00f3n de los<em> <\/em><a href=\"http:\/\/blogs.elcorreo.com\/index.php\/magonia\/2006\/04\/10\/\" target=\"_blank\"><em>magonianos<\/em><\/a>, pero yo me lo pas\u00e9 muy bien leyendo &#8216;El c\u00f3digo Da Vinci&#8217;, que me pareci\u00f3 una digna obra <em>pulp<\/em>, <em>trash<\/em> o como quieran llamarla, siempre que usen el ingl\u00e9s de los modernos. Como Brown se ha forrado, supongo que el t\u00edtulo de <em>Ed Wood literario<\/em> seguir\u00e1 en manos de <a href=\"http:\/\/www.harrystephenkeeler.com\" target=\"_blank\" rel=\"external nofollow\">Harry Stephen Keeler<\/a>, un escritor nacido en Chicago en 1890 que firm\u00f3 t\u00edtulos tan reveladores como &#8216;El caso del trapero enjoyado&#8217;, &#8216;El hombre de los t\u00edmpanos m\u00e1gicos&#8217;, &#8216;La misteriosa bola de marfil de Wong Shing Li&#8217; o &#8216;Yo mat\u00e9 a Lincoln a las 10:13&#8217;. S\u00f3lo he le\u00eddo un libro suyo, &#8216;El cuarto rey&#8217;, y no fue un camino de rosas, pero tampoco me arrepiento.<\/p>\n<p>Como buena parte de la humanidad, tuve mi primera noticia sobre la existencia de este autor a trav\u00e9s de <a href=\"http:\/\/www.harrystephenkeeler.com\/_el_personaje_mondobrutto.html\" target=\"_blank\" rel=\"external nofollow\">un art\u00edculo<\/a> publicado en <a href=\"http:\/\/www.mondobrutto.com\/\" target=\"_blank\" rel=\"external nofollow\">Mondo Brutto<\/a> por Alberto Sob\u00f3rnez, el tipo que tocaba el bajo en &#8216;Aqu\u00ed no hay playa&#8217;. Sob\u00f3rnez es un coleccionista y un impresionante conocedor de la obra de Keeler, profusamente editada en Espa\u00f1a entre los 40 y los 60 por la Editorial Reus. De hecho, hubo una \u00e9poca en la que este se\u00f1or S\u00d3LO ten\u00eda editor en Espa\u00f1a, ya que el resto del mundo hab\u00eda dado la espalda a sus argumentos imprevisibles, desconcertantes o abiertamente demenciales. Le copio a Sob\u00f3rnez el punto de partida de &#8216;El caso del cuerpo loco&#8217;: \u00abLa Polic\u00eda saca un ata\u00fad del lago Michigan. En el interior se encuentra un cuerpo desnudo: la mitad superior pertenece a una mujer china y la inferior a un hombre de raza negra\u00bb. Otros libros empiezan de manera m\u00e1s normal, pero pueden tomar derroteros de incre\u00edble osad\u00eda, es decir, de camisa de fuerza, aunque eso tambi\u00e9n ocurre en obras de autores m\u00e1s respetables como Boris Vian. Alg\u00fan fan tarado ha sido capaz de programar un <a href=\"http:\/\/staff.xu.edu\/%7Epolt\/keeler\/plot.html\" target=\"_blank\" rel=\"external nofollow\">generador de argumentos<\/a> de Keeler -en ingl\u00e9s, <em>sorry<\/em>&#8211; e incluso existe una <a href=\"http:\/\/xavier.xu.edu:8000\/%7Epolt\/keeler.html\" target=\"_blank\" rel=\"external nofollow\">sociedad<\/a> consagrada al devoto estudio de su obra. A veces, la serie Z prevalece: \u00a1a ver qui\u00e9n estudia a Dan Brown dentro de cuarenta a\u00f1os!<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El post de Arrieta sobre el generador de argumentos de Dan Brown me ha reafirmado en la idea de que, si este hombre no hubiese triunfado, alg\u00fan d\u00eda lo reivindicar\u00edan como un ap\u00f3stol de la novela de serie B, como una especie de Ed Wood del thriller literario. S\u00e9 que la siguiente frase puede acarrearme [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1249,1747],"class_list":["post-170","post","type-post","status-publish","format-standard","hentry","category-inclasificables","tag-harry-stephen-keeler","tag-literatura"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/170\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}