{"id":1689,"date":"2012-07-20T17:06:34","date_gmt":"2012-07-20T16:06:34","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1689"},"modified":"2012-07-20T17:06:34","modified_gmt":"2012-07-20T16:06:34","slug":"cancion-de-la-semana-cuernavaca","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/07\/20\/cancion-de-la-semana-cuernavaca\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Cuernavaca&#039;"},"content":{"rendered":"<p><a href=\"http:\/\/philcohran.com\/\" target=\"_blank\" rel=\"external nofollow\">Kelan Philip Cohran<\/a> es un venerable m\u00fasico de 85 a\u00f1os conocido, sobre todo, por sus aportaciones como trompetista a la Arkestra del extraterrestre <a href=\"https:\/\/www.google.com\/search?hl=en&#038;q=%22sun%20ra%22&#038;psj=1&#038;bav=on.2,or.r_gc.r_pw.r_cp.r_qf.,cf.osb&#038;biw=1540&#038;bih=807&#038;um=1&#038;ie=UTF-8&#038;tbm=isch&#038;source=og&#038;sa=N&#038;tab=wi&#038;ei=T4EJUK-xFcqo0QXN79SmCg\" target=\"_blank\">Sun Ra<\/a>. Hace un par de meses\u00a0 ha editado un \u00e1lbum junto al <a href=\"http:\/\/www.hypnoticbrassensemble.com\/\" target=\"_blank\" rel=\"external nofollow\">Hypnotic Brass Ensemble<\/a>, un conjunto en el que militan ocho de sus hijos. Parece mentira que todav\u00eda les queden ganas de tocar con el padre, teniendo en cuenta el r\u00e9gimen totalitario de educaci\u00f3n musical al que les someti\u00f3 cuando eran cr\u00edos: ellos mismos relatan que, por las noches, no pod\u00edan dormir porque el bueno de Phil estaba abajo, ensayando con sus colegas, y por las ma\u00f1anas les hac\u00eda levantarse a las seis para tener unas horitas de pr\u00e1ctica musical antes de ir al colegio.<\/p>\n<p><em>Cuernavaca<\/em>, el tema que abre el disco (y ya siento ser tan recurrente en esto de seleccionar las primeras canciones de los \u00e1lbumes, pero por algo las colocan ah\u00ed), est\u00e1 dedicado a la ciudad hom\u00f3nima del sur de M\u00e9xico, donde Cohran padre toc\u00f3 de joven, all\u00e1 por 1950. A m\u00ed me suena un poco f\u00fanebre, no s\u00e9, a lo mejor es por las connotaciones taurinas y <em>semanasanteras<\/em> de los metales.<\/p>\n<p>Despu\u00e9s de dos canciones de la semana instrumentales, a ver si el viernes que viene les traigo a alguien que les cante. Ahora, que suene la tuba&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/eWjupXpntHU?rel=0\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Kelan Philip Cohran es un venerable m\u00fasico de 85 a\u00f1os conocido, sobre todo, por sus aportaciones como trompetista a la Arkestra del extraterrestre Sun Ra. Hace un par de meses\u00a0 ha editado un \u00e1lbum junto al Hypnotic Brass Ensemble, un conjunto en el que militan ocho de sus hijos. Parece mentira que todav\u00eda les queden [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,654,1317,1427,1569,1966,2332],"class_list":["post-1689","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-cuernavaca","tag-hypnotic-brass-ensemble","tag-jazz","tag-kelan-philip-cohran","tag-mexico","tag-phil-cohran"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1689"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1689\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}