{"id":1532,"date":"2012-05-01T18:15:08","date_gmt":"2012-05-01T17:15:08","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1532"},"modified":"2012-05-01T18:15:08","modified_gmt":"2012-05-01T17:15:08","slug":"algunos-sonidos-de-mayo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/05\/01\/algunos-sonidos-de-mayo\/","title":{"rendered":"Algunos sonidos de mayo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1533\" title=\"Hidrogenesse, Carlos Ballesteros y Gen\u00eds Segarra\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse.jpg\" alt=\"\" width=\"559\" height=\"384\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse.jpg 1131w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse-150x103.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse-300x206.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse-768x528.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/05\/Hidrogenesse-600x413.jpg 600w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ser\u00e1 el efecto del primer d\u00eda de sol tras un mes de lluvia, pero la verdad es que me ha salido una selecci\u00f3n de conciertos la mar de rara, sin representantes de lo que podr\u00edamos llamar el rock m\u00e1s convencional. Estupendo, \u00bfno? Ah\u00ed les van cinco citas en cinco salas distintas, con unos bonitos comentarios abiertos para que cada cual proponga otras majaradas que le apetece ver.<\/p>\n<p><strong>Russian Circles y Deafheaven (Azkena, viernes 11).<\/strong> Tengo la sensaci\u00f3n de que <a href=\"http:\/\/www.youtube.com\/watch?v=A2-hJtJrXxc\" target=\"_blank\" rel=\"external nofollow\">Russian Circles<\/a>, el primero de los dos grupos de Chicago que aparecen en esta lista, se han convertido en estrellas del <em>underground<\/em>, porque me los encuentro citados por un mont\u00f3n de sitios. Y est\u00e1n muy bien, pero, si les soy sincero, los que a m\u00ed me atraen de verdad son los californianos <a href=\"http:\/\/www.youtube.com\/watch?v=-S08Af4fqso\" target=\"_blank\" rel=\"external nofollow\">Deafheaven<\/a>, una de esas bandas que estiran las costuras del black metal (<em>falso<\/em> black metal, puntualizar\u00e1n algunos) para hacer hueco a su infinita melancol\u00eda. Hala.<\/p>\n<p><strong>Tortoise (Sala BBK, domingo 13).<\/strong> Tambi\u00e9n vienen de Chicago los <a href=\"http:\/\/www.youtube.com\/watch?v=TIC-2poEdIE\" target=\"_blank\" rel=\"external nofollow\">padres del post rock<\/a>, a los que siempre reprochar\u00e9 la chapa infinita que dieron con ellos algunos medios guays a mediados de los 90. Ya s\u00e9 que no es culpa suya: ellos se limitaron a combinar en una lenta batidora los sonidos que les gustaban (rock progresivo, jazz, dub&#8230;) y dejar que el resultado les llevase por parajes poco transitados. Desde luego, la Sala BBK parece el lugar ideal para seguirles en el viaje.<\/p>\n<p><strong>La Casa Azul e Hidrogenesse (Santana 27, s\u00e1bado 19).<\/strong> Me pasa un poco lo mismo que antes: <a href=\"http:\/\/www.youtube.com\/watch?v=qKvrSNqRqEE\" target=\"_blank\" rel=\"external nofollow\">La Casa Azul<\/a> son cabeza de cartel en este concierto, y su hiperactivo pop tecnificado siempre merece la pena, pero yo tengo debilidad por <a href=\"http:\/\/www.youtube.com\/watch?v=_Ja175rKYg8\" target=\"_blank\" rel=\"external nofollow\">Hidrogenesse<\/a>, Carlos Ballesteros y Gen\u00eds Segarra, de quienes me fascina hasta el aspecto. Son los de la foto de arriba, claro. Me estoy dando cuenta, por cierto, de que a lo mejor esta lista no es tan dispar: \u00bfno podr\u00edan encajar Russian Circles, Tortoise y los Hidrogenesse m\u00e1s germ\u00e1nicos en un concierto?<\/p>\n<p><strong>Rabih Abou-Khalil &#038; Mediterranean Quintet (Teatro Campos, jueves 24).<\/strong> Tard\u00e9 un poco en caer, porque no es tan f\u00e1cil recordar el nombre de este liban\u00e9s virtuoso del oud, pero resulta que yo escuch\u00e9 mucho dos de sus \u00e1lbumes hace unos a\u00f1os, incluso los destaqu\u00e9 entre los discos inactuales que <a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2008\/12\/30\/viva-inactualidad\/\" target=\"_blank\">m\u00e1s me gustaron en 2007<\/a>. Es atmosf\u00e9rico jazz \u00e1rabe, con un pie en el folclore y otro en la vanguardia.<\/p>\n<p><del><strong>Ariel Ardit &#038; Orquesta T\u00edpica (Arriaga, jueves 31).<\/strong> No todos los d\u00edas tenemos la oportunidad de escuchar a un cantante como <a href=\"http:\/\/www.youtube.com\/watch?v=GHwugfK2hUQ\" target=\"_blank\" rel=\"external nofollow\">Ariel Ardit<\/a>, impecable en sus hechuras ortodoxas, acompa\u00f1ado por una orquesta t\u00edpica de piano, tres violines, viola, cuatro bandoneones y contrabajo. \u00bfNo se acelera ya su coraz\u00f3n tanguero?<\/del>\u00a0\u00a0 <strong>Como pueden imaginar, este bonito tach\u00f3n significa que el concierto ha sido cancelado.<\/strong><\/p>\n<p>Les dejo con Rabih Abou-Khalil, en una fant\u00e1stica sucesi\u00f3n de solos sobre su <em>Lewinsky March.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Rabih Abou-Khalil &quot;Lewinsky March&quot; - Solos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/brmo8LtwNOU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Ser\u00e1 el efecto del primer d\u00eda de sol tras un mes de lluvia, pero la verdad es que me ha salido una selecci\u00f3n de conciertos la mar de rara, sin representantes de lo que podr\u00edamos llamar el rock m\u00e1s convencional. Estupendo, \u00bfno? Ah\u00ed les van cinco citas en cinco salas distintas, con unos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[200,327,602,711,1276,1637,2444,2562,3081],"class_list":["post-1532","post","type-post","status-publish","format-standard","hentry","category-musica","tag-ariel-ardit","tag-bilbao","tag-conciertos","tag-deafheaven","tag-hidrogenesse","tag-la-casa-azul","tag-rabih-abou-khalil","tag-russian-circles","tag-tortoise"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1532"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1532\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}