{"id":1479,"date":"2012-04-17T19:18:05","date_gmt":"2012-04-17T18:18:05","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1479"},"modified":"2012-04-17T19:18:05","modified_gmt":"2012-04-17T18:18:05","slug":"spanish-horror-story","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/04\/17\/spanish-horror-story\/","title":{"rendered":"Spanish Horror Story"},"content":{"rendered":"<p>No tengo muy claro en qu\u00e9 fecha dicen los mayas que va a llegar el Apocalipsis, pero ya se empiezan a registrar signos preocupantes: leo con cierta angustia en la agencia <a href=\"http:\/\/www.efe.com\/\" target=\"_blank\" rel=\"external nofollow\">Efe<\/a> que Los del R\u00edo han lanzado hoy mismo <em>V\u00e1monos que nos vamos<\/em>, un trabajo que \u00abrezuma optimismo\u00bb en el que revisan \u00aben clave africana\u00bb su mayor \u00e9xito, <em>Macarena<\/em>. Ya saben, esa canci\u00f3n que vendi\u00f3 catorce millones de copias y que cumple veinte a\u00f1os en 2013, circunstancia que dar\u00eda de s\u00ed para una nueva versi\u00f3n si el mundo siguiese existiendo. Hay m\u00e1s. El d\u00fao andaluz tambi\u00e9n ha retomado el cl\u00e1sico <em>Sevilla tiene un color especial<\/em>, con los \u00abcoros, palmas, jaleo y alegr\u00eda\u00bb de Curro Romero, Victorio &#038; Lucchino, El Cordob\u00e9s, Eva Gonz\u00e1lez y Mar\u00eda Jos\u00e9 Su\u00e1rez. Y, para rematar, interpretan cl\u00e1sicos como el <em>Rock de la c\u00e1rcel<\/em> de Elvis, el <em>No puedo quitar mis ojos de ti<\/em> o la ranchera <em>El rey<\/em>&#8230; Solo falta que le dediquen esta \u00faltima a su amigo Juan Carlos, para el que han cantado en alguna ocasi\u00f3n.<\/p>\n<p>He pensado que todos ustedes deb\u00edan estar al tanto de esta noticia antes de salir a la calle, porque, en cuanto uno se descuida, Los del R\u00edo pueden atacar desde cualquier megafon\u00eda o hilo musical. Miren aqu\u00ed abajo la terrible mutaci\u00f3n que sufrieron en 1998 unos candidatos dem\u00f3cratas por Massachusetts, gente seria y profesional, cuando empez\u00f3 a sonar la <em>Macarena<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1481\" title=\"RODRIGUEZ YERARDI CLAPROOD\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1.jpg\" alt=\"\" width=\"546\" height=\"371\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1.jpg 620w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1-150x102.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1-300x204.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/04\/Macarena1-600x408.jpg 600w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No tengo muy claro en qu\u00e9 fecha dicen los mayas que va a llegar el Apocalipsis, pero ya se empiezan a registrar signos preocupantes: leo con cierta angustia en la agencia Efe que Los del R\u00edo han lanzado hoy mismo V\u00e1monos que nos vamos, un trabajo que \u00abrezuma optimismo\u00bb en el que revisan \u00aben clave [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,1674,1783,1841,3161],"class_list":["post-1479","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-lanzamientos","tag-los-del-rio","tag-macarena","tag-versiones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1479"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1479\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}