{"id":1224,"date":"2012-02-22T11:48:36","date_gmt":"2012-02-22T10:48:36","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1224"},"modified":"2012-02-22T11:48:36","modified_gmt":"2012-02-22T10:48:36","slug":"el-retorno-de-joey-ramone","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2012\/02\/22\/el-retorno-de-joey-ramone\/","title":{"rendered":"El retorno de Joey Ramone"},"content":{"rendered":"<p>Da un poco de miedo la historia con la que presenta <a href=\"http:\/\/www.rollingstone.com\/music\/blogs\/alternate-take\/joey-ramone-rocks-again-on-new-lp-20120221\" target=\"_blank\" rel=\"external nofollow\"><em>Rolling Stone<\/em><\/a> la historia del nuevo \u00e1lbum de Joey Ramone, el difunto Joey Ramone. Cuentan en el primer p\u00e1rrafo que, tras la muerte del vocalista de los Ramones en 2001, su madre y su hermano peque\u00f1o Mickey -con quien form\u00f3 el proyecto Sibling Rivalry- se pusieron a limpiar su apartamento de Nueva York y encontraron una cuenta de la pizzer\u00eda en la que hab\u00eda unas letras garrapateadas. \u00abLa cabeza de Joey estaba trabajando en algo\u00bb, concluye Mickey.<\/p>\n<p>Menos mal que, seg\u00fan parece, este <em>Ya Know?<\/em> que se editar\u00e1 en mayo se sustenta en algo m\u00e1s s\u00f3lido que unos versos manchados de pepperoni. No es que eso le quite la pinta de exprimidor de mitos, pero al menos se trata de maquetas que Joey grab\u00f3 en tiempos de los Ramones y despu\u00e9s de la disoluci\u00f3n del grupo, incluidas versiones alternativas de temas conocidos. Estuvieron a punto de reclutar a \u00abestrellas de bandas muy populares\u00bb para completar la grabaci\u00f3n, pero al final han tirado de amigos del larguirucho Joey, como Joan Jett, Steven Van Zandt o miembros de los Dictators y Cheap Trick. A lo mejor las letras de la pizza sirven para otro \u00e1lbum.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/02\/Joey.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1225\" title=\"Joey Ramone publica el disco p\u00f3stumo 'Ya Know?'\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2012\/02\/Joey.jpg\" alt=\"\" width=\"518\" height=\"527\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Da un poco de miedo la historia con la que presenta Rolling Stone la historia del nuevo \u00e1lbum de Joey Ramone, el difunto Joey Ramone. Cuentan en el primer p\u00e1rrafo que, tras la muerte del vocalista de los Ramones en 2001, su madre y su hermano peque\u00f1o Mickey -con quien form\u00f3 el proyecto Sibling Rivalry- [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,1469,2182,2462],"class_list":["post-1224","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-joey-ramone","tag-novedades","tag-ramones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1224"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1224\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}