{"id":1173,"date":"2011-12-30T17:00:41","date_gmt":"2011-12-30T16:00:41","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1173"},"modified":"2011-12-30T17:00:41","modified_gmt":"2011-12-30T16:00:41","slug":"rescate-de-canciones-saxana","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2011\/12\/30\/rescate-de-canciones-saxana\/","title":{"rendered":"Rescate de canciones: &#039;Saxana&#039;"},"content":{"rendered":"<p>Me asombra la cantidad de joyas del pasado que son capaces de resucitar los muchachos del sello <a href=\"http:\/\/www.finderskeepersrecords.com\" target=\"_blank\" rel=\"external nofollow\">Finders Keepers<\/a>, pero a veces tambi\u00e9n pienso que tendr\u00e1n que escuchar cientos y cientos de elep\u00e9s sin ning\u00fan inter\u00e9s para dar al final con esas maravillas. Entre sus exhumaciones de este a\u00f1o destaca la banda sonora de otra pel\u00edcula checa (hace a\u00f1os ya deslumbraron con <em>Valerie And Her Week Of Wonders<\/em>). Esta se titula <em>Saxan<\/em>a, cuenta la historia de una ni\u00f1a bruja y, por lo que veo, es tremendamente popular en la Rep\u00fablica Checa, donde marc\u00f3 a toda una generaci\u00f3n de ni\u00f1os de principios de los 70. Como a lo mejor a\u00fan no han decidido qu\u00e9 ver en nochevieja, les comunico con gusto que <a href=\"http:\/\/www.youtube.com\/watch?v=RfYk8UcLjV0\" target=\"_blank\" rel=\"external nofollow\">aqu\u00ed<\/a> la tienen entera con subt\u00edtulos en ingl\u00e9s, pero \u00edbamos a la m\u00fasica, un compendio de \u00abjazz psicod\u00e9lico\u00bb firmado por Angelo Michajlov que tiene como gancho m\u00e1s inmediato el tema central, cantado por la actriz protagonista, Petra Cernock\u00e1, una <em>harrypotter<\/em> crecidita y de pelo rizado. Bueno, la chica que ven aqu\u00ed abajo, en la imagen fija del v\u00eddeo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Saxana Theme\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/cFAykQakqtQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me asombra la cantidad de joyas del pasado que son capaces de resucitar los muchachos del sello Finders Keepers, pero a veces tambi\u00e9n pienso que tendr\u00e1n que escuchar cientos y cientos de elep\u00e9s sin ning\u00fan inter\u00e9s para dar al final con esas maravillas. Entre sus exhumaciones de este a\u00f1o destaca la banda sonora de otra [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[264,462,564,1030,2605],"class_list":["post-1173","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bandas-sonoras","tag-canciones","tag-cine","tag-finders-keepers","tag-saxana"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}