{"id":1163,"date":"2011-12-23T11:41:25","date_gmt":"2011-12-23T10:41:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1163"},"modified":"2011-12-23T11:41:25","modified_gmt":"2011-12-23T10:41:25","slug":"ur-ur-dangarin","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2011\/12\/23\/ur-ur-dangarin\/","title":{"rendered":"Ur-ur-dangar\u00edn"},"content":{"rendered":"<p>Hay gente que infravalora la relevancia que tuvo en los ochenta <a href=\"http:\/\/unpinguino.amigus.info\/\" target=\"_blank\" rel=\"external nofollow\">Un Ping\u00fcino en mi Ascensor<\/a>, el proyecto de pop de dormitorio del minimalista y jovial Jos\u00e9 Luis Moro Valent\u00edn-Gamazo, pero les aseguro que muchos miembros de mi generaci\u00f3n son capaces de recitar entera alguna de sus canciones de largu\u00edsima letra. A lo mejor mi caso es un poco m\u00e1s grave, porque me ha tocado tratar en mi vida con dos fans radicales de este hombre, que los hay, est\u00e1n sueltos y son peligrosos. El caso es que a\u00fan canturreo a menudo cosas como \u00abmaldigo a Mariano Medina cada vez que las nubes ocultan el sol\u00bb, por mucho que los j\u00f3venes me miren con el recelo de quien no conoce al Ping\u00fcino, ni mucho menos a Mariano Medina. El amigo Jos\u00e9 Luis vuelve a estar hoy de actualidad por esta bonita versi\u00f3n de Boney M dedicada a I\u00f1aki Urdangar\u00edn y su malet\u00edn, interpretada en directo con las bases pregrabadas y los contundentes guitarrazos del hist\u00f3rico Mario Gil, el de La Mode y <em>El precio justo<\/em>, y con la contribuci\u00f3n sampleada de Juan Carlos I,\u00a0 esa <em>rock star<\/em>. Qu\u00e9 contento estar\u00e1 Ur-ur-dangar\u00edn de que le homenajeen con una canci\u00f3n tan bonita&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Un ping\u00fcino en mi ascensor - Urdangarin HD\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/RihpClVmYdI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay gente que infravalora la relevancia que tuvo en los ochenta Un Ping\u00fcino en mi Ascensor, el proyecto de pop de dormitorio del minimalista y jovial Jos\u00e9 Luis Moro Valent\u00edn-Gamazo, pero les aseguro que muchos miembros de mi generaci\u00f3n son capaces de recitar entera alguna de sus canciones de largu\u00edsima letra. A lo mejor mi [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[397,992,1298,1337,3130],"class_list":["post-1163","post","type-post","status-publish","format-standard","hentry","category-musica","tag-boney-m","tag-familia-real","tag-homenajes","tag-inaki-urdangarin","tag-un-pinguino-en-mi-ascensor"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1163\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}