{"id":1107,"date":"2011-11-19T10:01:28","date_gmt":"2011-11-19T09:01:28","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1107"},"modified":"2011-11-19T10:01:28","modified_gmt":"2011-11-19T09:01:28","slug":"cancion-de-la-semana-all-we-ever-wanted-was-everything","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2011\/11\/19\/cancion-de-la-semana-all-we-ever-wanted-was-everything\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;All We Ever Wanted Was Everything&#039;"},"content":{"rendered":"<p>Me he pasado buena parte de mi vida explicando que no me gustan mucho Bauhaus. Cada vez que alg\u00fan aficionado al siniestrismo ochentero se enteraba de mi pasi\u00f3n por los Cure y Joy Division, no tardaban en aparecer Bauhaus en la conversaci\u00f3n, y yo siempre me escaqueaba diciendo que bueno, que s\u00ed, que estaban bien, que ten\u00edan su punto pero no me parec\u00edan lo mismo. A lo mejor mi mala relaci\u00f3n con ellos fue un simple caso de mala suerte en nuestro primer contacto: no s\u00e9 muy bien por qu\u00e9, me compr\u00e9 <em>Burning From The Inside<\/em>, que no es precisamente su obra m\u00e1s compacta, aunque arranque muy bien con la intimidante <em>She\u2019s In Parties<\/em>. Ya nunca llegu\u00e9 a reconciliarme del todo con lo que me parec\u00eda un exceso de teatralidad.<\/p>\n<p>As\u00ed que, en un ejemplo de coherencia, aqu\u00ed les traigo una canci\u00f3n de Bauhaus en fiel versi\u00f3n de MGMT, que la han incluido en su <a href=\"http:\/\/en.wikipedia.org\/wiki\/Late_Night_Tales:_MGMT\" target=\"_blank\" rel=\"external nofollow\">muy recomendable selecci\u00f3n<\/a> para la serie <em>Late Night Tales<\/em>. Se trata de <em>All We Ever Wanted Was Everything<\/em>, ya lo han visto en el t\u00edtulo, y&#8230; creo que acabo de darme cuenta de que me encanta.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"MGMT - All We Ever Wanted Was Everything (Animated) - Late Night Tales\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Okr5nL-3gfQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me he pasado buena parte de mi vida explicando que no me gustan mucho Bauhaus. Cada vez que alg\u00fan aficionado al siniestrismo ochentero se enteraba de mi pasi\u00f3n por los Cure y Joy Division, no tardaban en aparecer Bauhaus en la conversaci\u00f3n, y yo siempre me escaqueaba diciendo que bueno, que s\u00ed, que estaban bien, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[283,461,1968,3161],"class_list":["post-1107","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bauhaus","tag-cancion-de-la-semana","tag-mgmt","tag-versiones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}