{"id":1093,"date":"2011-11-13T22:45:05","date_gmt":"2011-11-13T21:45:05","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=1093"},"modified":"2011-11-13T22:45:05","modified_gmt":"2011-11-13T21:45:05","slug":"cancion-de-la-semana-on-the-run","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2011\/11\/13\/cancion-de-la-semana-on-the-run\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;On The Run&#039;"},"content":{"rendered":"<p>El 3 de diciembre tengo un compromiso que consiste b\u00e1sicamente en inflarme a comer y beber, as\u00ed que no voy a quejarme, pero esa brusca inmersi\u00f3n en colesterol y alcohol me impedir\u00e1 asistir a uno de los conciertos m\u00e1s interesantes de este final de a\u00f1o: el de The Horrors en el Kafe Antzokia. Soy de los que prefieren el primer \u00e1lbum de los Horrors a las reconversiones que han venido despu\u00e9s, pero aun as\u00ed me apetec\u00eda ver c\u00f3mo traducen al directo sus diversos estilos. Y tambi\u00e9n ten\u00eda muchas ganas de ver a los teloneros, los neoyorquinos <a href=\"http:\/\/www.cerebralballzy.com\/\" target=\"_blank\" rel=\"external nofollow\">Cerebral Ballzy<\/a>, autores de nuestra canci\u00f3n de esta semana. Estos muchachos son apasionados del skate y el hardcore de los 80, y no voy a negar a estas alturas que esa no es la descripci\u00f3n que m\u00e1s me motiva en el mundo, pero me encanta su sonido bronquista y c\u00f3mo retuercen las canciones en repentinos ganchos mel\u00f3dicos, sencill\u00edsimos pero efectivos, como la repetici\u00f3n \u00a0del t\u00edtulo de esta canci\u00f3n: on the run, on the run\u2026 Y es tan corta y tan urgente que, cuando acaba, apetece o\u00edrla de nuevo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"CEREBRAL BALLZY - ON THE RUN - HC WORLDWIDE (OFFICIAL VERSION HCWW)\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/RuVnlOzYe-w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El 3 de diciembre tengo un compromiso que consiste b\u00e1sicamente en inflarme a comer y beber, as\u00ed que no voy a quejarme, pero esa brusca inmersi\u00f3n en colesterol y alcohol me impedir\u00e1 asistir a uno de los conciertos m\u00e1s interesantes de este final de a\u00f1o: el de The Horrors en el Kafe Antzokia. Soy de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,511,602,2189],"class_list":["post-1093","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-cerebral-ballzy","tag-conciertos","tag-nueva-york"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=1093"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/1093\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=1093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=1093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}