{"id":847,"date":"2011-12-29T10:37:48","date_gmt":"2011-12-29T09:37:48","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=847"},"modified":"2011-12-29T10:37:48","modified_gmt":"2011-12-29T09:37:48","slug":"diario-de-invierno-de-paul-auster-otra-novela-autobiografica","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2011\/12\/29\/diario-de-invierno-de-paul-auster-otra-novela-autobiografica\/","title":{"rendered":"Diario de Invierno, de Paul Auster, otra novela autobiogr\u00e1fica"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2011\/12\/29\/diario-de-invierno-de-paul-auster-otra-novela-autobiografica\/1224253878130_1\/\" rel=\"attachment wp-att-848\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-848\" title=\"1224253878130_1\" src=\"\/estoesbrooklyn\/wp-content\/uploads\/sites\/10\/2011\/12\/1224253878130_1.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-content\/uploads\/sites\/10\/2011\/12\/1224253878130_1.jpg 360w, https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-content\/uploads\/sites\/10\/2011\/12\/1224253878130_1-300x241.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Paul Auster vuelve en 2012, como ya hemos anunciado, con la obra titulada Diario de Invierno (Winter&#8217;s Journal). Quienes esperen una nueva novela de ficci\u00f3n del estadounidense se ver\u00e1n desilusionados, porque el libro en cuesti\u00f3n es una suerte de segunda parte de sus memorias vitales. Si la primera, La Invencvi\u00f3n de la Soledad, escrita en los primeros a\u00f1os 80, se centra en el figura de su padre, en esta ocasi\u00f3n Auster repasa parte de su vida centr\u00e1ndose en su madre, en su divorcio y en la enfermedad terminal que acab\u00f3 con su vida. Auster repasa, de acuerdo a diferentes medios como <a href=\"http:\/\/www.thebookseller.com\/news\/second-work-memoir-auster.html\" rel=\"external nofollow\">The Book Seller<\/a>, otros episodios de su vida con su primera mujer, Lydia Davis, y con su actual esposa, Siri Hustvedt. Diario de Invierno aborda tambi\u00e9n sus crisis de ansiedad tras la muerte de su madre y otros hitos vitales como, seg\u00fan avanza su propia editorial anglosajona, sus protestas contra la guerra de Vietnam en la Universidad de Columbia.<\/p>\n<p>Los trabajos de ficci\u00f3n de Auster son habitualmente un grato entretenimiento de lectura, pero sus reflexiones biogr\u00e1ficas no lo son menos, as\u00ed que se puede esperar un libro interesante. Quiz\u00e1 sin el tir\u00f3n de la ficci\u00f3n, de sus historias dentro de las historias y sus referencias metaliterarias, pero puede ayudar a profundizar en la figura de un escritor que en febrero cumplir\u00e1 los 65 a\u00f1os y que mantiene una ferviente legi\u00f3n de seguidores.<\/p>\n<p>En Espa\u00f1a se ha anunciado <a href=\"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2011\/10\/13\/lo-nuevo-de-paul-auster-diario-de-invierno-en-febrero\/\">la nueva novela para febrero<\/a>, pero Anagrama a\u00fan no lo confirma.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Paul Auster vuelve en 2012, como ya hemos anunciado, con la obra titulada Diario de Invierno (Winter&#8217;s Journal). Quienes esperen una nueva novela de ficci\u00f3n del estadounidense se ver\u00e1n desilusionados, porque el libro en cuesti\u00f3n es una suerte de segunda parte de sus memorias vitales. Si la primera, La Invencvi\u00f3n de la Soledad, escrita en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-847","post","type-post","status-publish","format-standard","hentry","category-paul-auster-2","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=847"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/847\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}