{"id":83,"date":"2008-06-10T06:13:00","date_gmt":"2008-06-10T06:13:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=83"},"modified":"2008-06-10T06:13:00","modified_gmt":"2008-06-10T06:13:00","slug":"auster-lectura-paris","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/06\/10\/auster-lectura-paris\/","title":{"rendered":"Auster: Lectura en Par\u00eds"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp0.blogger.com\/_LSCWnEpAnto\/SE6cU8iRmjI\/AAAAAAAAAZ0\/xr72K_-1L6w\/s1600-h\/book469.jpg\"><IMG style=\"margin: 0px auto 10px; display: block; text-align: center; cursor: pointer;\" src=\"\/\/bp0.blogger.com\/_LSCWnEpAnto\/SE6cU8iRmjI\/AAAAAAAAAZ0\/xr72K_-1L6w\/s400\/book469.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5210273702575446578\" border=\"0\"><\/a>[<A href=\"http:\/\/blogs.iht.com\/tribtalk\/travel\/globespotters\/?p=435\">v\u00eda IHT<\/a>] Una de las atracciones literarias de Par\u00eds es la tradicional librer\u00eda <A href=\"http:\/\/www.shakespeareco.org\/\">Shakespeare and Co.<\/a>, en la canalla orilla izquierda<A href=\"http:\/\/maps.google.fr\/maps?f=q&#038;hl=en&#038;geocode=&#038;q=Square+R%C3%A9n%C3%A8+Viviani+paris&#038;sll=47.15984,2.988281&#038;sspn=10.563749,29.355469&#038;ie=UTF8&#038;ll=48.852443,2.347346&#038;spn=0.004991,0.014334&#038;t=h&#038;z=17\"> a un paso de Notre Dame<\/a>, que data de 1951 y que ha curtido su leyenda por el parentesco con Walt Whitman de su propietario, por ser la referencia en literatura anglosajona en la capital francesa y por su programa de acogimiento de escritores n\u00f3madas a los que se procuraba alojamiento y a cambio de algo de trabajo en el establecimiento. En unos d\u00edas celebrar\u00e1 su tercer <A href=\"http:\/\/www.festivalandco.com\/\">Festival and Co.<\/a>, con importante presencia de escritores anglosajones y franc\u00f3fonos. Destaca para nosotros la presencia de Paul Auster, que se anuncia para el s\u00e1bado 14 a las dos de la tarde, cuando leer\u00e1 un fragmento de su \u00faltima novela, <A href=\"http:\/\/paulauster.blogspot.com\/2008\/03\/primera-visita-de-auster-australia.html\">Man in the Dark<\/a>, a\u00fan no publicada en Estados Unidos ni tampoco en Espa\u00f1a. Tambi\u00e9n es buena oportunidad para escuchar a Amelie Nothomb, la interesante y polifac\u00e9tica escritora belga. El viernes 13 el centro de atenci\u00f3n ser\u00e1 la esposa de Auster, Siri Hustvedt, invitada a una sesi\u00f3n de lectura y debate acerca de su libro m\u00e1s reciente, <A href=\"http:\/\/paulauster.blogspot.com\/2008\/02\/siri-hustvedt-y-sorrows-of-american.html\">The sorrows of an American<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>[v\u00eda IHT] Una de las atracciones literarias de Par\u00eds es la tradicional librer\u00eda Shakespeare and Co., en la canalla orilla izquierda a un paso de Notre Dame, que data de 1951 y que ha curtido su leyenda por el parentesco con Walt Whitman de su propietario, por ser la referencia en literatura anglosajona en la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-83","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}