{"id":781,"date":"2010-06-21T18:52:00","date_gmt":"2010-06-21T18:52:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=781"},"modified":"2010-06-21T18:52:00","modified_gmt":"2010-06-21T18:52:00","slug":"dormir-la-habitacion-paul-auster","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2010\/06\/21\/dormir-la-habitacion-paul-auster\/","title":{"rendered":"Dormir en la habitaci\u00f3n &#039;Paul Auster&#039;"},"content":{"rendered":"<p><IMG src=\"\/estoesbrooklyn\/wp-content\/uploads\/sites\/10\/hotel.jpeg\" id=\"img_0\" class=\"imgizqda\">Reservar la habitaci\u00f3n &#8216;Paul Auster&#8217; ya es posible en Madrid. El hotel <A href=\"http:\/\/hotelsantodomingo.es\/\" title=\"http:\/\/hotelsantodomingo.es\/\" id=\"link_1\">Mercure Madrid Santo Domingo<\/a> (tiene <A href=\"http:\/\/unhotelenelcentrodemadrid.com\/blog\" title=\"http:\/\/unhotelenelcentrodemadrid.com\/blog\" id=\"link_2\">blog aqu\u00ed<\/a>), de la marca Mercure de la cadena Accor, ha abierto este nuevo establecimiento en el mismo coraz\u00f3n de la capital espa\u00f1ola (San Bernardo, 1, <A href=\"http:\/\/hotelsantodomingo.es\/localizacion.php?idioma=ES\" title=\"http:\/\/hotelsantodomingo.es\/localizacion.php?idioma=ES\" id=\"link_0\">muy cerca de la Gran V\u00eda<\/a>) y ha dotado de personalidad a sus habitaciones. Una de ellas est\u00e1 dedicada a Auster y Nueva York. Ya s\u00f3lo falta que el autor de Brooklyn se hospede en ella para que ascienda directamente a la categor\u00eda de m\u00edtica para sus seguidores. Lo vi en el <A href=\"http:\/\/paulauster.blogs.sapo.pt\/\" title=\"http:\/\/paulauster.blogs.sapo.pt\/\" id=\"link_3\">blog portugu\u00e9s sobre Auster<\/a>.<br \/>\nSi alg\u00fan d\u00eda\/noche la pruebo, os lo cuento.<br \/>\n<A href=\"http:\/\/www.infohoreco.es\/noticias\/detalle_noticia\/-\/asset_publisher\/O6cV\/content\/el-hotel-mercure-madrid-santo-domingo-abre-sus-puertas\" title=\"http:\/\/www.infohoreco.es\/noticias\/detalle_noticia\/-\/asset_publisher\/O6cV\/content\/el-hotel-mercure-madrid-santo-domingo-abre-sus-puertas\" id=\"link_0\">M\u00e1s info<\/a> sobre el hotel: <\/p>\n<blockquote><p>Habitaciones tematizadas de dise\u00f1o innovador. De sus 80 habitaciones, una es la Suite Unique y 79 son dobles.<br \/>\n La mayor singularidad de este proyecto supone que 12 de las habitaciones y sus ba\u00f1os han sido <strong>tematizados de forma diferenciada del resto<\/strong>, incluyendo numerosos murales de ambientaci\u00f3n diversa, realizados por un equipo de j\u00f3venes artistas espa\u00f1oles.  Cada una de ellas recrea un ambiente distinto: China, Nueva York, una playa, la jungla, el interior de un acuario o la cinematogr\u00e1fica evocaci\u00f3n de Los p\u00e1jaros de Hitchock, que invitan al visitante a adentrarse en cada uno de estos mundos y vivir una experiencia \u00fanica dej\u00e1ndose seducir por las creaciones de estos artistas.<br \/>\n Est\u00e1 previsto que muchos clientes habituales del Santo Domingo \u201ccoleccionen\u201d habitaciones, eligiendo en cada ocasi\u00f3n una diferente. Las habitaciones tematizadas tienen nombre propio y son: Acuario, Impacto, Tropical, La siesta, Oriental, Butterflies, Los P\u00e1jaros, Arpegio, <strong>Paul Auster (Nueva York)<\/strong>, Mondrian, Don Quijote y Daliniana. Por su parte, la Suite, de 60 m2 y elegantemente decorada, ofrece unas excelentes vistas del Madrid de los Austrias, Palacio Real y la plaza Santo Domingo.<br \/>\nAdem\u00e1s, existen unas <strong>40 decoraciones distintas en habitaciones<\/strong> y ba\u00f1os como elemento diferenciador, prestando atenci\u00f3n a cada detalle, buscando la originalidad y el confort, en un gran esfuerzo de creatividad.  A<br \/>\ns\u00ed, los muebles, telas, pintura, acabados, ba\u00f1os, iluminaci\u00f3n de cada una de las habitaciones se ha dise\u00f1ado con la clara idea de crear un espacio muy especial. Se ha buscado crear espacios en habitaciones y ba\u00f1os que aporten novedad, variedad, originalidad y que perduren en el recuerdo como algo singular y fuera de lo habitual.<br \/>\nIgualmente, el hotel dispone de la m\u00e1xima innovaci\u00f3n en todas sus estancias, como el aislamiento ac\u00fastico de las habitaciones, cortinas que se manipulan desde la cama, armarios de dise\u00f1o, l\u00e1mparas hechas a medida; pero sobre todo se ha innovado en los ba\u00f1os.<br \/>\nTeniendo en cuenta que los hoteles envejecen por los ba\u00f1os ya que normalmente requieren obras traum\u00e1ticas y muy costosas, en el Santo Domingo se han dise\u00f1ado de f\u00e1cil renovaci\u00f3n, utilizando el cristal como el gran elemento de forrado de los paramentos.<br \/>\nOtros detalles innovadores son las duchas con cromoterapia, las paredes acristaladas, grifer\u00eda de dise\u00f1o, suelos con arena de playa, etc. <\/p><\/blockquote>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Reservar la habitaci\u00f3n &#8216;Paul Auster&#8217; ya es posible en Madrid. El hotel Mercure Madrid Santo Domingo (tiene blog aqu\u00ed), de la marca Mercure de la cadena Accor, ha abierto este nuevo establecimiento en el mismo coraz\u00f3n de la capital espa\u00f1ola (San Bernardo, 1, muy cerca de la Gran V\u00eda) y ha dotado de personalidad a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[54],"class_list":["post-781","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-paul-auster"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=781"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/781\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}