{"id":759,"date":"2010-04-27T13:00:00","date_gmt":"2010-04-27T13:00:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=759"},"modified":"2010-04-27T13:00:00","modified_gmt":"2010-04-27T13:00:00","slug":"neil-young-s-greendale-comic","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2010\/04\/27\/neil-young-s-greendale-comic\/","title":{"rendered":"Neil Young&#039;s Greendale; el comic"},"content":{"rendered":"<p><IMG src=\"\/estoesbrooklyn\/files\/sun-green-graphic-novel.jpg\" id=\"img_0\" class=\"imgcen\">Leo en <A href=\"http:\/\/enlaplayadeneil.blogspot.com\/2010\/04\/greendale-el-comic.html\" title=\"http:\/\/enlaplayadeneil.blogspot.com\/2010\/04\/greendale-el-comic.html\" id=\"link_0\">En la playa de Neil<\/a>, el blog de referencia en espa\u00f1ol sobre <A href=\"http:\/\/en.wikipedia.org\/wiki\/Neil_Young\" title=\"http:\/\/en.wikipedia.org\/wiki\/Neil_Young\" id=\"link_4\">Neil Young<\/a>, que est\u00e1 a punto de publicarse en USA un c\u00f3mic basado en el disco Greendale, un trabajo de Young datado en 2003 y ejecutado como disco conceptual, cuyas canciones narran una historia ocurrida en esa localidad imaginaria del norte de California. Greendale fue CD, concierto en directo (adjuntado como bonus con el disco original), libro y DVD, y ahora surge como novela gr\u00e1fica; es decir, comic. Ya se puede reseravr en la web de <A href=\"http:\/\/www.amazon.com\/Neil-Youngs-Greendale-Josh-Dysart\/dp\/1401226981\/ref=sr_1_1\/178-3911806-5366125?ie=UTF8&#038;s=books&#038;qid=1272112139&#038;sr=8-1\" title=\"http:\/\/www.amazon.com\/Neil-Youngs-Greendale-Josh-Dysart\/dp\/1401226981\/ref=sr_1_1\/178-3911806-5366125?ie=UTF8&#038;s=books&#038;qid=1272112139&#038;sr=8-1\" id=\"link_1\">Amazon<\/a>, donde se anuncia su lanzamiento para el 15 de junio.<br \/>\nGreendale es un claro disco de denuncia creado por Young en el ambiente post-11-S que llev\u00f3 a otros artistas a elaborar \u00e1lbumes de evidente calado pol\u00edtico, en particular a aquellos contrarios a la invasi\u00f3n de Iraq ordenada por Bush tras los ataques de Nueva York. Greendale es una \u00f3pera rock de diez temas que cuenta la historia de la saga Green. En los instrumentos est\u00e1n los chicos de <A href=\"http:\/\/es.wikipedia.org\/wiki\/Crazy_Horse_%28banda%29\" title=\"http:\/\/es.wikipedia.org\/wiki\/Crazy_Horse_%28banda%29\" id=\"link_2\">Crazy Horse<\/a>, en la que es hasta la fecha la \u00faltima colaboraci\u00f3n de Young con Molina, Talbot y compa\u00f1\u00eda.<br \/>\nNeil Young ha estado directamente involucrado en la adaptaci\u00f3n del disco al formato gr\u00e1fico, que ha estado a cargo del escritor Joshua Dysart y el artista Sean Murphy para la editorial <A href=\"http:\/\/www.publishersweekly.com\/article\/407838-Vertigo_Plans_Neil_Young_Graphic_Novel_New_Minx_Titles_.php\" title=\"http:\/\/www.publishersweekly.com\/article\/407838-Vertigo_Plans_Neil_Young_Graphic_Novel_New_Minx_Titles_.php\" id=\"link_3\">Vertigo<\/a>. El relato va a contar la historia de Sun Green, la adolescente de la familia, una muchacha comprometida pol\u00edticamente y con una clara conciencia ecologista, anticorrupci\u00f3n y pro-planeta.<br \/>\nGreendale es un gran disco de Young. Tuvo una repercusi\u00f3n modesta, pero fue aclamado por algunos cr\u00edticos. Desborda cr\u00edticas contra la corrupci\u00f3n, el ansia desmedida de los medios de comunicaci\u00f3n americanos, los ataques contra la madre tierra. No es un Harvest, son puros temas de rock, con composiciones que se van m\u00e1s all\u00e1 de los 10 y hasta 12 minutos de duraci\u00f3n. Son historias que conviene leer mientras se escuchan. El disco, en este sentido, ven\u00eda bien preparado, con un art-work notable en el interior del CD, plano de Greendale incluido.<br \/>\nImagen: Sun Green, by <A href=\"http:\/\/www.comicsbulletin.com\/vertigo\/images\/0808\/sun.jpg\" title=\"http:\/\/www.comicsbulletin.com\/vertigo\/images\/0808\/sun.jpg\" id=\"link_0\">Cliff Chiang<\/a> <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Leo en En la playa de Neil, el blog de referencia en espa\u00f1ol sobre Neil Young, que est\u00e1 a punto de publicarse en USA un c\u00f3mic basado en el disco Greendale, un trabajo de Young datado en 2003 y ejecutado como disco conceptual, cuyas canciones narran una historia ocurrida en esa localidad imaginaria del norte [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-759","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=759"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/759\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}