{"id":749,"date":"2010-03-30T16:51:00","date_gmt":"2010-03-30T16:51:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=749"},"modified":"2010-03-30T16:51:00","modified_gmt":"2010-03-30T16:51:00","slug":"ipad-hora-la-verdad","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2010\/03\/30\/ipad-hora-la-verdad\/","title":{"rendered":"iPad, la hora de la verdad"},"content":{"rendered":"<p><IMG src=\"\/estoesbrooklyn\/files\/ipad-3g.jpg\" id=\"img_0\" class=\"imgcen\" width=\"462\" height=\"270\">Tras meses de rumores, expectaci\u00f3n, elogios y premios al <em>fail <\/em>tecnologico del a\u00f1o, el iPad se la juega este fin de semana, cuando se comenzar\u00e1n a vender las primeras unidades del cacharrito de Apple en Estados Unidos. Como somos gente predecible, es seguro que habr\u00e1 colas en las tiendas de la manzanita m\u00e1s representativas para hacerse con uno. Lo que a\u00fan est\u00e1 por ver es que har\u00e1n esos felices compradores al d\u00eda siguiente. \u00bfLo utilizar\u00e1n como un iPod gigante? \u00bfVer\u00e1n videos? \u00bfLeer\u00e1n libros? \u00bfSimplemente lo sacar\u00e1n a la calle para fardar un rato? \u00bfDescargar\u00e1n alguna de las 100.000 aplicaciones (cerca de 99.000 absolutamente irrelevantes) con las que parece contar el aparatito?<br \/>\nApple se frota las manos. Algunas fuentes dicen (lo he le\u00eddo en el blog de <A href=\"http:\/\/www.enriquedans.com\/\" title=\"http:\/\/www.enriquedans.com\/\" id=\"link_1\">Enrique Dans<\/a>, as\u00ed que pr\u00e1cticamente va a misa), que se esperan unas ventas de<A href=\"http:\/\/mashable.com\/2010\/03\/29\/apple-10-million-ipads\/\" title=\"http:\/\/mashable.com\/2010\/03\/29\/apple-10-million-ipads\/\" id=\"link_0\"> entre 8 y 10 millones<\/a>  de iPads s\u00f3lo en 2010. Ser\u00e1 importante un buen inicio, tanto para desmoralizar a los rivales, si es que los hay, como para machacar las opiniones que lo reducen a un <A href=\"..\/estoesbrooklyn\/2010\/3\/12\/el-ipad-fiasco-tecnologico-del-ano\" title=\"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2010\/3\/12\/el-ipad-fiasco-tecnologico-del-ano\" id=\"link_3\">bluff tecnol\u00f3gico<\/a>  de proporciones cicl\u00f3peas.<br \/>\nEn mi opini\u00f3n, Apple no hacer experimentos con gaseosa. Pero tampoco me imagino con un iPad en las manos. \u00bfQu\u00e9 podr\u00eda hacer que no haga ya con mi iPhone? \u00bfSustituir\u00eda a mi port\u00e1til por el nuevo cacharrito? En fin, cu\u00e1nto estupor.<br \/>\n<A href=\"http:\/\/www.apple.com\/ipad\/gallery\/#ad\" title=\"http:\/\/www.apple.com\/ipad\/gallery\/#ad\" id=\"link_4\">El Ipad, en acci\u00f3n<\/a> | Videotutoriales en la web de Apple<br \/>\n<A href=\"http:\/\/www.applesfera.com\/tag\/especial-lanzamiento-ipad\" title=\"http:\/\/www.applesfera.com\/tag\/especial-lanzamiento-ipad\" id=\"link_2\">Applesfera <\/a> | Especial lanzamiento iPad<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tras meses de rumores, expectaci\u00f3n, elogios y premios al fail tecnologico del a\u00f1o, el iPad se la juega este fin de semana, cuando se comenzar\u00e1n a vender las primeras unidades del cacharrito de Apple en Estados Unidos. Como somos gente predecible, es seguro que habr\u00e1 colas en las tiendas de la manzanita m\u00e1s representativas para [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-749","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=749"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/749\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}