{"id":728,"date":"2010-01-28T11:25:00","date_gmt":"2010-01-28T11:25:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=728"},"modified":"2010-01-28T11:25:00","modified_gmt":"2010-01-28T11:25:00","slug":"resaca-del-ipad-apple-wins-again","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2010\/01\/28\/resaca-del-ipad-apple-wins-again\/","title":{"rendered":"Resaca del iPad, Apple wins again"},"content":{"rendered":"<p><IMG style=\"width: 500px; height: 365px;\" src=\"\/estoesbrooklyn\/wp-content\/uploads\/sites\/10\" id=\"img_0\" class=\"imgcen\">Se supone que para este momento ya te has enterado de lo b\u00e1sico. Apple anuncia nuevo cacharrito (el <A href=\"http:\/\/www.apple.com\/ipad\/\" title=\"http:\/\/www.apple.com\/ipad\/\" id=\"link_1\">iPad<\/a>); es una tableta t\u00e1ctil con forma de iPhone m\u00e1s grande; se parece tanto al iPhone que pr\u00e1cticamente sirve para lo mismo, pero no para llamar por tel\u00e9fono; es decir, es un <A href=\"http:\/\/pogue.blogs.nytimes.com\/\" title=\"http:\/\/pogue.blogs.nytimes.com\/\" id=\"link_2\">iPod Touch gigante<\/a>; tabletas ya exist\u00edan, pero nunca se te pas\u00f3 por la cabeza comprarte una; pero \u00e9sta s\u00ed la quieres, porque mola; Apple se lleva tu pasta otra vez.<br \/>\nEs curioso c\u00f3mo la compa\u00f1\u00eda de la manzanita logra convertir en &#8216;algo nuevo&#8217; cosas que ya exist\u00edan. &#8216;Redefine&#8217; el concepto de tablet, dec\u00edan ayer y hoy <A href=\"http:\/\/www.enriquedans.com\/\" title=\"http:\/\/www.enriquedans.com\/\" id=\"link_0\">los expertos<\/a>. Los tablet nunca cuajaron, a pesar de que parec\u00edan toda una modernez frente a los pesados port\u00e1tiles. Se pod\u00eda trabajar en ellos como quien escribe en un folio, pero nadie los compr\u00f3. Y sin embargo triunfaron los netbooks, ordenadorcitos con pantallas min\u00fasculas b\u00e1sicamente preparados para acceder a Internet.<br \/>\nEl iPad tiene la base de ambas cosas y a\u00f1ade dos m\u00e1s: la gran experiencia musical que proporciona iTunes y, como novedad, su servicio muy parecido para los libros electr\u00f3nicos, tambi\u00e9n con tienda propia (iBooks) y acuerdos forjados ya con las principales editoras americanas. El cacharrito tiene un modo de pantalla espec\u00edfico para leer libros y, por tama\u00f1o y peso, puede ser c\u00f3modo para ello.<br \/>\n<strong>Pros<\/strong>: Apple mola; ya sabemos manejarlo antes incluso de tenerlo en la mano; iBooks es una gran idea (esperamos con ansia iPress); el precio no es malo (desde 599 d\u00f3lares);<br \/>\n<strong>Contra<\/strong>: No tiene reconocimiento de escritura a mano (las viejas tablet s\u00ed lo hac\u00edan); \u00a1no tiene c\u00e1mara!; es demasiado parecido al iPod Touch; no flash,<em> as usual<\/em>; no multitarea.<br \/>\nComo cacharrito para el ocio est\u00e1 muy chulo, ahora s\u00f3lo hay que buscarle una utilidad pr\u00e1ctica.<br \/>\nAh, y ya s\u00f3lo nos faltan el iPed, el iPid y el iPud (<A href=\"http:\/\/twitter.com\/javier\/status\/8293007571\" title=\"http:\/\/twitter.com\/javier\/status\/8293007571\" id=\"link_3\">v\u00eda<\/a>)<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Se supone que para este momento ya te has enterado de lo b\u00e1sico. Apple anuncia nuevo cacharrito (el iPad); es una tableta t\u00e1ctil con forma de iPhone m\u00e1s grande; se parece tanto al iPhone que pr\u00e1cticamente sirve para lo mismo, pero no para llamar por tel\u00e9fono; es decir, es un iPod Touch gigante; tabletas ya [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[38],"class_list":["post-728","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-ipad"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}