{"id":67,"date":"2008-08-27T05:51:00","date_gmt":"2008-08-27T05:51:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=67"},"modified":"2008-08-27T05:51:00","modified_gmt":"2008-08-27T05:51:00","slug":"asi-arranca-un-hombre-la-oscuridad-nuevo-paul-auster","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/08\/27\/asi-arranca-un-hombre-la-oscuridad-nuevo-paul-auster\/","title":{"rendered":"As\u00ed arranca &#039;Un hombre en la oscuridad&#039;, lo nuevo de Paul Auster"},"content":{"rendered":"<p>Estoy solo en la oscuridad, d\u00e1ndole vueltas al mundo en la cabeza mientras paso otra noche de insomnio, otra noche en blanco en la gran desolaci\u00f3n americana. Arriba, mi hija y mi nieta est\u00e1n cada una en su habitaci\u00f3n, tambi\u00e9n solas: mi hija \u00fanica, Miriam, de cuarenta y siete a\u00f1os, que se acuesta sola desde hace cinco, y Katya, de veintitr\u00e9s, \u00fanica hija de Miriam, que antes dorm\u00eda con un joven llamado Titus Small, pero ahora Titus ha muerto, y mi nieta duerme sola con el coraz\u00f3n destrozado.<br \/>\nLuz radiante, y luego oscuridad. El sol fulgurando por todos los rincones del cielo, seguido de la negrura de la noche, el silencio de las estrellas, el viento que agita las ramas. \u00c9sa es la monoton\u00eda diaria. Llevo viviendo m\u00e1s de un a\u00f1o en esta casa, desde que me dieron de alta en el hospital. Miriam insisti\u00f3 en que viniera, y al principio est\u00e1bamos los dos solos, junto con la enfermera que me cuidaba durante el d\u00eda cuando mi hija se iba a trabajar. Luego, tres meses despu\u00e9s, a Katya se le cay\u00f3 el mundo encima, y entonces dej\u00f3 la escuela de cine en Nueva York y se vino a Vermont a vivir con su madre.<br \/>\n<A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/3.bp.blogspot.com\/_LSCWnEpAnto\/SLV-zA-TSPI\/AAAAAAAAAag\/OzmTvi4N-NQ\/s1600-h\/26643496.JPG\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/3.bp.blogspot.com\/_LSCWnEpAnto\/SLV-zA-TSPI\/AAAAAAAAAag\/OzmTvi4N-NQ\/s400\/26643496.JPG\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5239233156415178994\" border=\"0\"><\/a>Sus padres lo llamaron como al hijo de Rembrandt, ese peque\u00f1o de los cuadros, el ni\u00f1o de cabellos dorados y gorro escarlata, el pupilo distra\u00eddo que no comprende la lecci\u00f3n, la criatura transformada en un joven devastado por la enfermedad que muri\u00f3 a los veintitantos a\u00f1os, igual que el Titus de Katya. Es un nombre maldito, un nombre que deber\u00eda retirarse para siempre de la circulaci\u00f3n. Pienso a menudo en el fin de Titus, la horrorosa historia de su \u00faltimo trance, las im\u00e1genes de su agon\u00eda, las demoledoras consecuencias de su muerte en mi atribulada nieta, pero no quiero entrar en eso ahora, no puedo caer en ello, tengo que alejarlo lo m\u00e1s posible de mi pensamiento. La noche a\u00fan es joven, y sin moverme de la cama, con los ojos clavados en la oscuridad, en una tiniebla tan impenetrable que no se alcanza a ver el techo, me pongo a recordar la historia que empec\u00e9 anoche. Eso es lo que hago cuando no logro conciliar el sue\u00f1o. Me quedo tumbado en la cama y me cuento historias. Quiz\u00e1 no sean gran cosa, pero siempre y cuando no me salga de ellas, me evitan pensar en cosas que prefiero olvidar. La concentraci\u00f3n, sin embargo, puede darme problemas, y las m\u00e1s de las veces mis pensamientos acaban derivando de la historia que pretendo contar a las cosas en las cuales no quiero pensar. No hay nada que hacer. Fracaso una y otra vez, hay m\u00e1s chascos que aciertos, pero eso no quiere decir que no ponga todo mi empe\u00f1o.<br \/>\nLo met\u00ed en un hoyo. Parec\u00eda un buen comienzo, una prometedora manera de poner las cosas en marcha. Situar a un hombre dormido en un pozo, para luego ver lo que pasa cuando se despierte e intente salir trepando. Me refiero a una profunda concavidad en el suelo, de unos tres metros de honda, excavada en forma de c\u00edrculo perfecto, con paredes verticales de tierra s\u00f3lida, muy compacta, tan dura que la superficie tiene una textura de arcilla modelada, de vidrio incluso. En otras palabras, cuando el hombre abra los ojos no conseguir\u00e1 salir del hoyo. A menos que disponga de una serie de aparejos de monta\u00f1a -martillo y crampones, por ejemplo, o una cuerda para echar un lazo a un \u00e1rbol cercano-, pero este hombre no tiene herramientas, y una vez que recobre la conciencia, enseguida comprender\u00e1 la naturaleza del aprieto en que se encuentra.<br \/>\nY as\u00ed es. El hombre se despierta y descubre que est\u00e1 tendido de espaldas, mirando al cielo de un atardecer sin nubes. Se llama Owen Brick, y no tiene ni idea de c\u00f3mo ha ido a parar all\u00ed, no guarda recuerdo alguno de c\u00f3mo ha ca\u00eddo en ese agujero cil\u00edndrico, que seg\u00fan sus c\u00e1lculos tendr\u00e1 aproximadamente tres metros y medio de di\u00e1metro. Se incorpora. Para su sorpresa, va vestido con un uniforme parduzco de lana \u00e1spera. Tiene la cabeza cubierta con una gorra, y lleva un par de robustas y gastadas botas de cuero negro, bien atadas por encima de los tobillos con una doble lazada. En las mangas de la chaqueta ostenta dos galones, lo que indica que el uniforme pertenece a un militar con el rango de cabo. Esa persona podr\u00eda ser Owen Brick, pero el hombre del hoyo, cuyo nombre es Owen Brick, no recuerda haber servido en el ej\u00e9rcito ni combatido en guerra alguna en ning\u00fan momento de su vida.<br \/>\nA falta de otra explicaci\u00f3n, supone que ha perdido temporalmente la memoria a consecuencia de alg\u00fan golpe recibido en la cabeza. Sin embargo, al pasarse la punta de los dedos por el cuero cabelludo en busca de rasgu\u00f1os o chichones, no encuentra indicios de bultos, ni heridas ni ara\u00f1azos, nada que sugiera la existencia de ese golpe. \u00bfQu\u00e9 ha sido, entonces? \u00bfHa sufrido alg\u00fan trauma que le ha mermado las facultades, haci\u00e9ndole perder el uso de gran parte del cerebro? Tal vez. Pero a menos que le venga de pronto el recuerdo de ese trauma, no tendr\u00e1 medio de saberlo. Seguidamente, empieza a explorar la posibilidad de que est\u00e9 durmiendo en la cama, en su casa, atrapado en un sue\u00f1o extra\u00f1amente l\u00facido, un sue\u00f1o tan veros\u00edmil y absorbente que la frontera entre lo real y lo imaginario se ha difuminado hasta casi desaparecer. Si eso es cierto, entonces no tiene m\u00e1s que abrir los ojos, levantarse de la cama y dirigirse a la cocina a prepararse el caf\u00e9 del desayuno. Pero \u00bfc\u00f3mo se pueden abrir los ojos cuando ya est\u00e1n abiertos? Parpadea unas cuantas veces, en un intento pueril de romper el encantamiento; pero no hay hechizo alguno, y la cama m\u00e1gica no llega a materializarse.<br \/>\nEn lo alto, una bandada de estorninos atraviesa su campo de visi\u00f3n durante cinco o seis segundos, desapareciendo luego hacia el crep\u00fasculo. Brick se pone en pie para inspeccionar su entorno, y entonces nota que le abulta un objeto en el bolsillo delantero izquierdo del pantal\u00f3n. Resulta ser una cartera, la suya, y adem\u00e1s de setenta y seis d\u00f3lares estadounidenses, contiene un carn\u00e9 de conducir expedido por el Estado de Nueva York a un tal Owen Brick, nacido el 12 de junio de 1977. Eso confirma lo que Brick ya sabe: que es un individuo cercano a la treintena con domicilio en Jackson Heights, en el barrio de Queens. Sabe asimismo que est\u00e1 casado con una mujer llamada Flora y que durante los \u00faltimos siete a\u00f1os ha trabajado como mago profesional, actuando principalmente en fiestas de aniversario infantiles por toda la ciudad con el nombre art\u00edstico del Gran Zavello. Tales hechos no hacen sino ahondar el misterio. Si tan seguro est\u00e1 de qui\u00e9n es, \u00bfc\u00f3mo ha acabado entonces en el fondo de ese pozo, vestido con uniforme de cabo, nada menos, sin documentos, ni placa ni identificaci\u00f3n que acredite su condici\u00f3n militar?<br \/>\nNo tarda mucho en comprender que escapar de all\u00ed es totalmente imposible. La pared circular es muy alta, y cuando le da un puntapi\u00e9 con la bota con idea de hacer una marca y crear una especie de punto de apoyo que le permita escalarla, s\u00f3lo consigue hacerse da\u00f1o en el dedo gordo. La noche cae r\u00e1pidamente, y va haciendo fr\u00edo, un fr\u00edo h\u00famedo de primavera que le va calando hasta los huesos, y aunque ha empezado a tener miedo, de momento est\u00e1 m\u00e1s confuso que asustado. Sin embargo, no puede por menos de gritar pidiendo auxilio. Hasta ahora, todo ha estado en silencio a su alrededor, se\u00f1al de que se encuentra en alg\u00fan lugar remoto y despoblado de la campi\u00f1a, sin m\u00e1s ruido que el ocasional grito de un p\u00e1jaro y el murmullo del viento. Como cumpliendo una orden, sin embargo, como obedeciendo a cierta l\u00f3gica sesgada de causa y efecto, en el momento en que grita la palabra socorro, un fragor de artiller\u00eda estalla a lo lejos, y el oscuro cielo se alumbra con cometas que van dejando una estela de destrucci\u00f3n. Brick oye ametralladoras, granadas que explotan, y bajo todo eso, sin duda a kil\u00f3metros de distancia, un apagado coro de alaridos humanos. Es la guerra, comprende entonces, y \u00e9l combate en ella, pero sin arma alguna a su disposici\u00f3n, no podr\u00e1 defenderse si lo atacan, y por primera vez desde que se despert\u00f3 en el hoyo, siente verdadero p\u00e1nico.<br \/>\nLas detonaciones se prolongan m\u00e1s de una hora, para luego disiparse poco a poco hasta que se hace el silencio. No mucho despu\u00e9s, Brick oye un tenue sonido de sirenas, que atribuye a coches de bomberos que acuden velozmente a los edificios da\u00f1ados durante el asalto. Luego, las sirenas se apagan a su vez y la calma desciende sobre \u00e9l una vez m\u00e1s. Adem\u00e1s de asustado y aterido de fr\u00edo, Brick est\u00e1 agotado, y tras pasear en torno a los confines de su c\u00e1rcel cil\u00edndrica hasta que las estrellas aparecen en el firmamento, se tiende en el suelo y logra dormir al fin.<br \/>\nA la ma\u00f1ana siguiente, muy temprano, lo despierta una voz que lo llama desde arriba del hoyo. Brick alza la cabeza y ve el rostro de un hombre asomado por el borde, y como s\u00f3lo puede verle la cara, supone que est\u00e1 tumbado boca abajo.<br \/>\n-Cabo -dice el desconocido-. Cabo Brick, es hora de marcharse.<br \/>\nBrick se pone en pie, y ahora que sus ojos est\u00e1n s\u00f3lo a un metro o metro treinta del rostro del desconocido, ve que se trata de un individuo de tez morena, mand\u00edbula cuadrada y barba de dos d\u00edas, que lleva una gorra militar id\u00e9ntica a la que \u00e9l tiene puesta en la cabeza. Antes de que Brick pueda protestar siquiera para decir que por mucho que desee largarse de all\u00ed no est\u00e1 en condiciones de hacerlo, el rostro del hombre desaparece.<br \/>\n-No te preocupes -le oye decir-. Te sacaremos de ah\u00ed en un periquete.<br \/>\nUnos momentos despu\u00e9s se oye el ruido de un martillo o un mazo golpeando sobre un objeto met\u00e1lico, y como el sonido se va apagando a cada golpe sucesivo, Brick se pregunta si el desconocido est\u00e1 hincando una estaca de hierro en el suelo. Porque si es as\u00ed, entonces puede que dentro de poco ate a la estaca una cuerda mediante la cual \u00e9l podr\u00e1 trepar y salir del hoyo. Cesa el ruido met\u00e1lico, pasan otros treinta o cuarenta segundos, y entonces, tal como Brick supon\u00eda, cae una cuerda a sus pies.<br \/>\nBrick practica la magia, no el culturismo, y aunque trepar por un metro de cuerda no constituya un esfuerzo excesivamente agotador para un hombre de treinta a\u00f1os en buen estado de salud, a \u00e9l en cambio le cuesta mucho izarse hasta arriba. La pared no le sirve de ayuda, pues la suela de las botas le resbala continuamente por la lisa superficie, y cuando intenta asegurar los pies en la cuerda, no consigue sujetarse bien, lo que supone que debe recurrir exclusivamente a la fuerza de los brazos, y como los suyos no son ni fuertes ni musculosos, y la cuerda es de un material \u00e1spero y, por tanto, le irrita la palma de las manos, esa sencilla operaci\u00f3n se convierte en una verdadera batalla. Cuando por fin llega al borde del pozo y el desconocido le da la mano derecha y tira de \u00e9l hasta ponerlo a nivel del suelo, Brick est\u00e1 sin aliento y asqueado de s\u00ed mismo. Tras una actuaci\u00f3n tan penosa, espera que su ineptitud sea objeto de burla, pero por alg\u00fan milagro el desconocido se abstiene de hacer comentario vejatorio alguno.<br \/>\nMientras se pone trabajosamente en pie, Brick observa que el uniforme de su salvador es igual que el suyo, con la \u00fanica excepci\u00f3n de que lleva tres galones en la manga, y no dos. Hay una espesa niebla en el ambiente, y le resulta dif\u00edcil hacerse una idea de d\u00f3nde se encuentra. En alg\u00fan sitio solitario del campo, tal como supon\u00eda, pero la ciudad o el pueblo que anoche fue v\u00edctima del ataque no se ve por parte alguna. Lo \u00fanico que distingue con claridad es la estaca de metal con la cuerda atada y un <em>jeep<\/em> lleno de barro estacionado a unos tres metros del hoyo.<br \/>\n-Cabo -dice el desconocido, tendiendo la mano a Brick y estrech\u00e1ndosela con un apret\u00f3n firme y entusiasta-. Soy tu sargento, Serge Tobak. Pero me suelen llamar Sarge Serge.Brick baja la cabeza y mira al desconocido, que por lo menos es quince cent\u00edmetros m\u00e1s bajo que \u00e9l, y repite con voz queda: Sarge Serge.<br \/>\n[v\u00eda <A href=\"http:\/\/www.elpais.com\/articulo\/portada\/Estoy\/solo\/oscuridad\/elpepipor\/20080803elpdmgrep_7\/Tes\/\">El Pa\u00eds<\/a>]<br \/>\nPrimeras impresiones en <A href=\"http:\/\/www.papelenblanco.com\/2008\/08\/08-un-hombre-en-la-oscuridad-de-paul-auster-primeras-impresiones\">Papel en Blanco<\/a>.<br \/>\nGu\u00eda de cr\u00edticas en <A href=\"http:\/\/paulauster.blogspot.com\/2008\/08\/man-in-dark-gua-de-crticas.html\">Esto es Brooklyn!<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estoy solo en la oscuridad, d\u00e1ndole vueltas al mundo en la cabeza mientras paso otra noche de insomnio, otra noche en blanco en la gran desolaci\u00f3n americana. Arriba, mi hija y mi nieta est\u00e1n cada una en su habitaci\u00f3n, tambi\u00e9n solas: mi hija \u00fanica, Miriam, de cuarenta y siete a\u00f1os, que se acuesta sola desde [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-67","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/67\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=67"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}