{"id":66,"date":"2008-08-27T05:51:00","date_gmt":"2008-08-27T05:51:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=66"},"modified":"2008-08-27T05:51:00","modified_gmt":"2008-08-27T05:51:00","slug":"murakami-tambien-este-otono","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/08\/27\/murakami-tambien-este-otono\/","title":{"rendered":"Murakami, tambi\u00e9n este oto\u00f1o"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/3.bp.blogspot.com\/_LSCWnEpAnto\/SLWD9j8R7dI\/AAAAAAAAAaw\/ErhRUqkhOvo\/s1600-h\/afterdark.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/3.bp.blogspot.com\/_LSCWnEpAnto\/SLWD9j8R7dI\/AAAAAAAAAaw\/ErhRUqkhOvo\/s320\/afterdark.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5239238835158773202\" border=\"0\"><\/a>Con el habitual retraso respecto a la publicaci\u00f3n original de sus novelas, parece que este oto\u00f1o toca por fin novedades de Haruki Murakami, quiz\u00e1 el escritor japon\u00e9s de mayor difusi\u00f3n internacional, con permiso de Oe y el resto de vacas sagradas niponas. <A href=\"http:\/\/paulauster.blogspot.com\/2007\/05\/after-dark-lo-nuevo-de-murakami.html\">Ya hablamos hace tiempo en este blo<\/a><A href=\"http:\/\/paulauster.blogspot.com\/2007\/05\/after-dark-lo-nuevo-de-murakami.html\">g<\/a> de After Dark, lo \u00faltimo de Murakami, publicado en ingl\u00e9s en 2007 pese a datar de 2004. Seg\u00fan <A href=\"http:\/\/www.elpais.com\/articulo\/cultura\/Auster\/Vila-Matas\/Murakami\/protagonizan\/otono\/literario\/elpepucul\/20080825elpepucul_2\/Tes\">El Pa\u00eds<\/a>, est\u00e1 en el cat\u00e1logo de Tusquets para estos meses, que tambi\u00e9n ver\u00e1n novedades de Doris Lessing, Philip Roth o John Boyne, el autor del pelotazo editorial &#8216;El ni\u00f1o del pijama de rayas&#8217;. <A href=\"http:\/\/secretgarden-5piaget5.blogspot.com\/2007\/05\/after-dark-by-haruki-murakami.html\">The Secret Garden<\/a> hizo una rese\u00f1a de After Dark y a <A href=\"http:\/\/cargadadelibros.wordpress.com\/2008\/08\/02\/lanzamiento-after-dark-de-haruki-murakami-en-octubre\/\">Cargadadelibros<\/a> le rob\u00e9 la portada y la sinopsis.<br \/>\n<span style=\"color: rgb(0, 0, 0); font-style: italic;\">Cerca ya de medianoche, Mari, sentada sola a la mesa de un restaurante, se toma un caf\u00e9, fuma y lee. Un joven la interrumpe: es Takahashi, un m\u00fasico al que ha visto una \u00fanica vez, en una cita de su hermana Eri, modelo profesional. \u00c9sta, mientras tanto, duerme en su habitaci\u00f3n, sumida en un sue\u00f1o profundo, \u201cdemasiado perfecto, demasiado puro\u201d. Mari ha perdido el \u00faltimo tren de vuelta a casa y piensa pasarse la noche leyendo en el restaurante; Takahashi se va a ensayar con su grupo, pero promete regresar antes del alba. Mari sufre una segunda interrupci\u00f3n: Kaoru, la encargada de un \u201chotel por horas\u201d, solicita su ayuda. Mari habla chino y una prostituta de esa nacionalidad ha sido brutalmente agredida por un cliente. Dan las doce. En la habitaci\u00f3n donde Eri sigue sumida en una dulce inconsciencia, el televisor cobra via y poco a poco empieza a distinguirse en la pantalla una imagen turbadora: una amplia sala amueblada con una \u00fanica silla en la que est\u00e1 sentado un hombre vestido de negro. Lo m\u00e1s importante es que el televisor no est\u00e1 enchufado\u2026<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Con el habitual retraso respecto a la publicaci\u00f3n original de sus novelas, parece que este oto\u00f1o toca por fin novedades de Haruki Murakami, quiz\u00e1 el escritor japon\u00e9s de mayor difusi\u00f3n internacional, con permiso de Oe y el resto de vacas sagradas niponas. Ya hablamos hace tiempo en este blog de After Dark, lo \u00faltimo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-66","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/66\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=66"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=66"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}