{"id":641,"date":"2006-01-20T05:12:00","date_gmt":"2006-01-20T05:12:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=641"},"modified":"2006-01-20T05:12:00","modified_gmt":"2006-01-20T05:12:00","slug":"el-primer-hombre-delgado","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/01\/20\/el-primer-hombre-delgado\/","title":{"rendered":"El primer hombre delgado"},"content":{"rendered":"<p> La editorial espa\u00f1ola <A href=\"http:\/\/www.seix-barral.es\/portada.asp\">Seix Barral <\/a>ha publicado <A href=\"http:\/\/www.seix-barral.es\/fichalibro.asp?libro=891\">El primer hombre delgado<\/a>, del maestro de la novela negra <A href=\"http:\/\/www.seix-barral.es\/fichaautor.asp?autor=424\">Dashiel Hammett (1894-1961)<\/a>, un relato in\u00e9dito hasta ahora en lengua castellana. La traducci\u00f3n est\u00e1 a cargo de Justo Navarro, habitual adaptador de los textos de Paul Auster para Anagrama.<br \/>\nEl relato tiene su historia. Fue publicado por primera vez en 1975 en la revista City Magazine, 45 a\u00f1os despu\u00e9s de haber sido escrito. En 1930, Dashiell Hammett redact\u00f3 estos diez cap\u00edtulos, originalmente pensados para la novela El Hombre Delgado. Pero dej\u00f3 el relato ah\u00ed, y las p\u00e1ginas que llevaba escritas pasaron de mano en mano y acabaron perdi\u00e9ndose.<br \/>\nM\u00e1s tarde, Hammett public\u00f3 por fin una novela con el t\u00edtulo de El Hombre Delgado, muy distinta en contenido a aquella que se esbozada en las p\u00e1ginas perdidas en 1930. &#8220;El detective profesional se hab\u00eda transformado en millonario aficionado a la investigaci\u00f3n criminal&#8230; El ruido de la calle y el tugurio hab\u00eda sido sustituido por la risa y la violencia en el sal\u00f3n, humor<br \/>\ny copas incesantes de la ma\u00f1ana a la ma\u00f1ana siguiente&#8230; &#8220;, se apunta en la web de Seix Barral. El Hombre Delgado fue un \u00e9xito y Hammett no volvi\u00f3 a publicar nada m\u00e1s. &#8220;El primer hombre delgado probablemente sea el \u00faltimo testimonio de novela negra aut\u00e9ntica, tal como Hammett la invent\u00f3&#8221;. Una buena oportunidad para descubrirlo.<br \/>\n<A href=\"http:\/\/www.imdb.com\/name\/nm0358591\/\">Filmograf\u00eda<\/a><\/p>\n<p>El Primer Hombre Delgado<br \/>\n128 p\u00e1gs.<br \/>\nPVP: 17,00 euros<br \/>\nISBN: 84-322-4312-4<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La editorial espa\u00f1ola Seix Barral ha publicado El primer hombre delgado, del maestro de la novela negra Dashiel Hammett (1894-1961), un relato in\u00e9dito hasta ahora en lengua castellana. La traducci\u00f3n est\u00e1 a cargo de Justo Navarro, habitual adaptador de los textos de Paul Auster para Anagrama. El relato tiene su historia. Fue publicado por primera [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-641","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=641"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/641\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}