{"id":616,"date":"2006-03-10T04:20:00","date_gmt":"2006-03-10T04:20:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=616"},"modified":"2006-03-10T04:20:00","modified_gmt":"2006-03-10T04:20:00","slug":"un-relato-endeble-j-m-prada","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/03\/10\/un-relato-endeble-j-m-prada\/","title":{"rendered":"Un relato &#8220;endeble&#8221; para J.M. de Prada"},"content":{"rendered":"<p>No todo iban a ser buenas cr\u00edticas, comentarios autocomplacientes o entusiastas llamadas a la compra y disfrute de Brooklyn Follies, lo \u00faltimo de Paul Auster. Para gustos est\u00e1n hechos los colores y es conveniente no caer en mitificaciones, as\u00ed que no duele en absoluto dar cuenta de una cr\u00edtica negativa hacia el libro que nos trae estos d\u00edas de cabeza. <A href=\"http:\/\/www.interrogantes.net\/includes\/seccion.php?IdSec=167\">Juan Manuel de Prada<\/a>, reconocido escritor y articulista espa\u00f1ol, controvertido, amado y odiado con regularidad, firma hoy una extenso comentario en el suplemento <A href=\"http:\/\/www.abc.es\/abcd\/noticia.asp?id=3505&#038;dia=&#038;sec=32\">ABCD las Artes  las Letras<\/a> del diario madrile\u00f1o <A href=\"http:\/\/www.abc.es\/\">ABC<\/a>. &#8220;Nos hallamos ante uno de los libros m\u00e1s endebles de Auster, demasiado confiado a la fascinaci\u00f3n natural de la escritura&#8221;, resume De Prada en el ante\u00faltimo p\u00e1rrafo de su &#8216;review&#8217;. Eso s\u00ed, el escritor no puede evitar arrebatarse ante la primera l\u00ednea del relato: &#8220;Estaba buscando un sitio tranquilo para morir, confiesa Nathan Glass al principio de la novela -escribe De Prada-, en uno de esos arranques irresistibles que suele dispensarnos Auster&#8221;. Pero lo mejor es leer el <A href=\"http:\/\/www.abc.es\/abcd\/noticia.asp?id=3505&#038;dia=&#038;sec=32\">comentario completo<\/a>, que hemos archivado en nuestra <A href=\"http:\/\/paulauster.blogspot.com\/2006\/03\/brooklyn-follies-gua-de-crticas-en.html\">Gu\u00eda de Comentarios<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No todo iban a ser buenas cr\u00edticas, comentarios autocomplacientes o entusiastas llamadas a la compra y disfrute de Brooklyn Follies, lo \u00faltimo de Paul Auster. Para gustos est\u00e1n hechos los colores y es conveniente no caer en mitificaciones, as\u00ed que no duele en absoluto dar cuenta de una cr\u00edtica negativa hacia el libro que nos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-616","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=616"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/616\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}