{"id":604,"date":"2006-04-01T04:07:00","date_gmt":"2006-04-01T04:07:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=604"},"modified":"2006-04-01T04:07:00","modified_gmt":"2006-04-01T04:07:00","slug":"la-palabra-mas-bonita","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/04\/01\/la-palabra-mas-bonita\/","title":{"rendered":"La palabra m\u00e1s bonita"},"content":{"rendered":"<p><A href=\"http:\/\/www.escueladeescritores.com\/modules.php?name=Actividades&#038;file=tienes-la-palabra\">Escueladeescritores.com<\/a> propone hasta el 20 de abril una de las iniciativas m\u00e1s curiosas: encontrar la palabra m\u00e1s bella de la lengua castellana. Abre el certamen con un buen ramillete de escritores que han prestado su palabra favorita, pero la ganadora, que se har\u00e1 p\u00fablica el D\u00eda del Libro, se elegir\u00e1 por cibervotaci\u00f3n popular a trav\u00e9s de Internet. La iniciativa ha recibido hoy un buen espaldarazo publicitario en <A href=\"http:\/\/www.elpais.es\/articulo\/elpporcul\/20060401elpepicul_1\/Tes\/cultura\/palabra\/bonita\/espanol\">El Pa\u00eds<\/a>, as\u00ed que se espera un seguimiento masivo.<br \/>\nAna Mar\u00eda Matute ha elegido <A href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual?TIPO_HTML=2&#038;LEMA=resplandor\">resplandor<\/a>.<br \/>\nArturo P\u00e9rez Reverte, <A href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual?TIPO_HTML=2&#038;LEMA=ultramarinos\">ultramarinos<\/a>.<br \/>\nJorge M. Reverte ha elegido <A href=\"http:\/\/buscon.rae.es\/draeI\/SrvltGUIBusUsual?TIPO_HTML=2&#038;LEMA=albahaca\">albahaca<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Escueladeescritores.com propone hasta el 20 de abril una de las iniciativas m\u00e1s curiosas: encontrar la palabra m\u00e1s bella de la lengua castellana. Abre el certamen con un buen ramillete de escritores que han prestado su palabra favorita, pero la ganadora, que se har\u00e1 p\u00fablica el D\u00eda del Libro, se elegir\u00e1 por cibervotaci\u00f3n popular a trav\u00e9s [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-604","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=604"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/604\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}