{"id":602,"date":"2006-04-07T04:06:00","date_gmt":"2006-04-07T04:06:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=602"},"modified":"2006-04-07T04:06:00","modified_gmt":"2006-04-07T04:06:00","slug":"adaptan-al-teatro-la-venda-hustvedt","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/04\/07\/adaptan-al-teatro-la-venda-hustvedt\/","title":{"rendered":"Adaptan al teatro &#039;La venda&#039;, de Hustvedt"},"content":{"rendered":"<p> La actriz, dramaturga y directora teatral argentina <A href=\"http:\/\/www.alternativateatral.com\/ficha_persona.asp?codigo_persona=60\">Gabriela Izcovich<\/a> ha estrenado en La Carbonera, uno de los teatros alternativos de Buenos Aires, su adaptaci\u00f3n de la primera novela de Siri Hustvedt, <A href=\"http:\/\/www.alternativateatral.com\/ficha_obra.asp?codigo_obra=5994\">La Venda<\/a>. Es la historia de Iris (Siri al rev\u00e9s, un anagrama que <A href=\"http:\/\/paulauster.blogspot.com\/2005\/12\/auster-y-los-nombres.html\">tambi\u00e9n ha utilizado Paul Auster<\/a>), una mujer que se ve involucrada en varias historias en las que desgrana su identidad y el sentido de su vida. Rodeada de cuatro hombres y de un asesinato no resuelto, se trata de una obra de estados y emociones que, de momento, ha recibido <A href=\"http:\/\/www.lanacion.com.ar\/entretenimientos\/nota.asp?nota_id=794938\">fr\u00edas cr\u00edticas<\/a>. Hustvedt visitar\u00e1 Buenos Aires en fechas pr\u00f3ximas, ya que participar\u00e1 junto a un buen ramillete de escritores anglosajones e hispano hablantes (P\u00e9rez Reverte, Laura Esqu\u00edvel, Jaime Bayly, entre otros) en la <A href=\"http:\/\/www.clarin.com\/diario\/2006\/03\/31\/sociedad\/s-04515.htm\">feria internacional del libro<\/a> de la capital argentina.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La actriz, dramaturga y directora teatral argentina Gabriela Izcovich ha estrenado en La Carbonera, uno de los teatros alternativos de Buenos Aires, su adaptaci\u00f3n de la primera novela de Siri Hustvedt, La Venda. Es la historia de Iris (Siri al rev\u00e9s, un anagrama que tambi\u00e9n ha utilizado Paul Auster), una mujer que se ve involucrada [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-602","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=602"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/602\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}