{"id":591,"date":"2006-04-21T03:41:00","date_gmt":"2006-04-21T03:41:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=591"},"modified":"2006-04-21T03:41:00","modified_gmt":"2006-04-21T03:41:00","slug":"reedicion-a-salto-mata","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/04\/21\/reedicion-a-salto-mata\/","title":{"rendered":"Reedici\u00f3n de A Salto de Mata"},"content":{"rendered":"<p> Nos hacemos eco de la rese\u00f1a de J.A. Gurpegui en la revista El Cultural, de <A href=\"http:\/\/www.elmundo.es\/\">El Mundo<\/a>, publicada ayer, sobre la reedici\u00f3n de A Salto de Mata:<br \/>\n<span style=\"font-style: italic;\">Tal vez pudiera existir alguna que otra discrepancia al establecer la lista los autores norteamericanos m\u00e1s populares en Espa\u00f1a, pero desde luego que si se buscara el consenso en uno de ellos \u00e9ste ser\u00eda Paul Auster. Ahora se reedita en bolsillo A salto de mata, probablemente su obra m\u00e1s autobiogr\u00e1fica y en la que conocemos a un Auster que inicia su andadura en el dif\u00edcil mundo de las letras. &#8220;Cuando llegu\u00e9 a la treintena, pas\u00e9 por unos a\u00f1os en los cuales todo lo que tocaba se convert\u00eda en un fracaso&#8221;. Su juvenil e incorruptible \u00edmpetu se ve mediatizado por mil y un condicionantes, como su familia y su obsesi\u00f3n por el dinero, llegando a plantearse situaciones c\u00f3micas e inquietantes.<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nos hacemos eco de la rese\u00f1a de J.A. Gurpegui en la revista El Cultural, de El Mundo, publicada ayer, sobre la reedici\u00f3n de A Salto de Mata: Tal vez pudiera existir alguna que otra discrepancia al establecer la lista los autores norteamericanos m\u00e1s populares en Espa\u00f1a, pero desde luego que si se buscara el consenso [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-591","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=591"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/591\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}