{"id":551,"date":"2006-06-08T01:20:00","date_gmt":"2006-06-08T01:20:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=551"},"modified":"2006-06-08T01:20:00","modified_gmt":"2006-06-08T01:20:00","slug":"extracto-viajes-el-scriptorium","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/06\/08\/extracto-viajes-el-scriptorium\/","title":{"rendered":"Extracto de &#039;Viajes en el Scriptorium&#039;"},"content":{"rendered":"<p> La revista <A href=\"http:\/\/www.elcultural.es\/HTML-web\/CINE\/dvdteca.asp\">El Cultural<\/a>, que se entrega los jueves con el peri\u00f3dico madrile\u00f1o El Mundo, publica hoy un extracto de la nueva novela de Paul Auster, que traducen como <A href=\"http:\/\/paulauster.blogspot.com\/2006\/01\/en-marcha-una-nueva-novela.html\">Viajes en el Scriptorium <\/a>(Travels in the Scriptorium). La publicaci\u00f3n avanza una veintena de p\u00e1rrafos (a\u00fan no colgados en su web: actualizar\u00e9 en cuanto los detecte[<A href=\"http:\/\/www.elcultural.es\/HTML\/20060608\/Letras\/LETRAS17543.asp\">actualizo: aqu\u00ed est\u00e1<\/a>]) que hace part\u00edcipe al lector de una peque\u00f1a trama de suspense muy al estilo de la Trilog\u00eda de Nueva York, obra la que m\u00e1s me ha recordado su lectura. El Cultural no aclara si se trata de los primeros p\u00e1rrafos de la novela o de un pasaje interior, detalle clave para dar mayor o menor importancia a la primera l\u00ednea del texto: &#8220;El anciano est\u00e1 sentado al borde de la estrecha cama, con las manos apoyadas en las rodillas, la cabeza gacha, la vista fija en el suelo&#8221;.<br \/>\nEn el extracto que reproduce la revista espa\u00f1ola, enseguida nos damos cuenta de que el anciano (m\u00e1s adelante, <A href=\"http:\/\/paulauster.blogspot.com\/2005\/12\/auster-y-los-nombres.html\">M\u00edster Blank<\/a>), est\u00e1 encerrado en una peque\u00f1a habitaci\u00f3n desde hace un tiempo que no recuerda, en pijama, en actitud ausente, olvidadiza, &#8220;perdido entre los fantasmas que pueblan su imaginaci\u00f3n mientras busca una respuesta a la pregunta que le atormenta&#8221;, dice Auster. El autor juega con este peque\u00f1o suspense. \u00bfQu\u00e9 hace el anciano ah\u00ed? \u00bfQu\u00e9 le atormenta? &#8220;Lo que s\u00ed sabe es que est\u00e1 consumido por un implacable complejo de culpa&#8221;, dice m\u00e1s adelante.<br \/>\nEl anciano es grabado en todo momento por una c\u00e1mara fotogr\u00e1fica asida al techo (que hace una fotograf\u00eda cada segundo) y por micr\u00f3fonos en las paredes que registran todos sus ruidos. En la habitaci\u00f3n hay montones de papeles y fotograf\u00edas &#8220;pulcramente colocados sobre el escritorio de caoba&#8221;. Los examina, observa una fotograf\u00eda de mujer y musita &#8220;Anna&#8221; y coge un texto mecanografiado que Auster va incluyendo en el relato. El texto parece haber sido escrito por el anciano y relata que ha sido golpeado por militares, torturado hasta quedar sin sentido: &#8220;desde entonces me tienen en esta habitaci\u00f3n&#8221;, sigue el escrito, que M\u00edster Blank lee con con angust\u00eda.<br \/>\nHasta aqu\u00ed el avance, que intentar\u00e9 obtener en su originalidad. El relato est\u00e1 previsto que se publique a finales de a\u00f1o. La traducci\u00f3n parece encargada a Benito G\u00f3mez Ib\u00e1\u00f1ez, traductor habitual de Paul Auster en Espa\u00f1a.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La revista El Cultural, que se entrega los jueves con el peri\u00f3dico madrile\u00f1o El Mundo, publica hoy un extracto de la nueva novela de Paul Auster, que traducen como Viajes en el Scriptorium (Travels in the Scriptorium). La publicaci\u00f3n avanza una veintena de p\u00e1rrafos (a\u00fan no colgados en su web: actualizar\u00e9 en cuanto los detecte[actualizo: [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-551","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=551"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/551\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}