{"id":546,"date":"2006-06-25T01:15:00","date_gmt":"2006-06-25T01:15:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=546"},"modified":"2006-06-25T01:15:00","modified_gmt":"2006-06-25T01:15:00","slug":"coney-island-baby-30-anos-y-reedicion","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/06\/25\/coney-island-baby-30-anos-y-reedicion\/","title":{"rendered":"Coney Island Baby: 30 a\u00f1os y reedici\u00f3n"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/photos1.blogger.com\/blogger\/6859\/954\/1600\/Cover-LouReed-Coney.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/photos1.blogger.com\/blogger\/6859\/954\/320\/Cover-LouReed-Coney.jpg\" alt=\"\" border=\"0\"><\/a>Grandes \u00e1lbumes cumplen este a\u00f1o su <A href=\"http:\/\/www.billboard.com\/bbcom\/news\/article_display.jsp?vnu_content_id=1002727576\">trig\u00e9simo aniversario<\/a>, una fecha que las majors no dejan pasar si el m\u00fasico sigue en activo y con visos de tir\u00f3n comercial. Ocurri\u00f3 con <A href=\"http:\/\/paulauster.blogspot.com\/2005\/10\/30-aos-de-born-to-run.html\">Born To Run<\/a>, de Springsteen \u2013doble CD y DVD con material in\u00e9dito y en directo\u2013 y va a ocurrir ahora con <A href=\"http:\/\/en.wikipedia.org\/wiki\/Coney_Island_Baby\">Coney Island Baby<\/a> de Lou Reed. El disco, de 1976, no es lo mejor del neoyorquino, ni un \u00e1lbum de referencia, pero incluye algunas de las mejores canciones de Reed. Para mi gust\u00f3, dos sublimes (<span style=\"font-style: italic;\">Coney Island Baby<\/span> y <span style=\"font-style: italic;\">She&#8217;s my Best Friend<\/span>), una obra intensa (<span style=\"font-style: italic;\">A Gift<\/span>) y un arranque alegre y prometedor (<span style=\"font-style: italic;\">Crazy Feeling<\/span>). Es el sexto \u00e1lbum de estudio de Reed tras la ruptura de The Velvet Underground y no se puede abordar su cr\u00edtica sin atender al contexto: Se escribi\u00f3 y public\u00f3 despu\u00e9s del experimento llamado <A href=\"http:\/\/en.wikipedia.org\/wiki\/Metal_Machine_Music\">Metal Machine Music<\/a>, el doble \u00e1lbum donde s\u00f3lo se puede escuchar una hora de intensa distorsi\u00f3n, como la herramienta de un dentista amplificada a m\u00e1ximo volumen con la que Reed, desde un profundo desafio creativo, puso a prueba a los fans que auparon su anterior LP, el mediocre Sally Can&#8217;t Dance, al Top Ten (el \u00fanico del neoyorquino en su carrera). Abatido, endeudado y quiz\u00e1 arrepentido de la travesura, Reed grab\u00f3 Coney Island Baby, ocho temas que finalizan a coraz\u00f3n abierto: con el rockero cantando a la <span style=\"font-style: italic;\">gloria del amor<\/span> susurrando a Rachel, el travesti que por entonces era su novia: <span style=\"font-style: italic;\">t\u00edo, sabes que lo dejar\u00eda todo por ti<\/span>.<br \/>\nConey Island Baby (RCA\/Legacy) <A href=\"http:\/\/www.billboard.com\/bbcom\/news\/article_display.jsp?vnu_content_id=1002727576\">se reedita en agosto<\/a> con rarezas, caras B, algunos cortes de las sesiones del disco (Leave Me Alone, Downtown Dirt, ya editados en la caja Between Thoughts and Expression, de 1992) e interesantes versiones alternativas de los temas principales del \u00e1lbum, algunos en colaboraci\u00f3n del ex Velvet Doug Yule.<br \/>\n<A href=\"http:\/\/www.lyricsfreak.com\/l\/lou+reed\/coney+island+baby_20085123.html\">Lyrics<\/a><br \/>\n<A href=\"http:\/\/www.treblezine.com\/reviews\/852.html\">Review<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Grandes \u00e1lbumes cumplen este a\u00f1o su trig\u00e9simo aniversario, una fecha que las majors no dejan pasar si el m\u00fasico sigue en activo y con visos de tir\u00f3n comercial. Ocurri\u00f3 con Born To Run, de Springsteen \u2013doble CD y DVD con material in\u00e9dito y en directo\u2013 y va a ocurrir ahora con Coney Island Baby de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-546","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=546"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/546\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}