{"id":538,"date":"2006-07-24T01:03:00","date_gmt":"2006-07-24T01:03:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=538"},"modified":"2006-07-24T01:03:00","modified_gmt":"2006-07-24T01:03:00","slug":"estrenan-argentina-hide-seek-paul-auster","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/07\/24\/estrenan-argentina-hide-seek-paul-auster\/","title":{"rendered":"Estrenan en Argentina &#039;Hide &#038; Seek&#039;, de Paul Auster"},"content":{"rendered":"<p>El director teatral argentino Mariano Dossena nos escribe para comunicarnos el estreno, el pr\u00f3ximo 4 de agosto en Buenos Aires (sala La Tertulia), de la adaptaci\u00f3n que ha realizado de la obra de Paul Auster <em>Hide and Seek<\/em>, uno de los textos teatrales escritos por el neoyorquino en los a\u00f1os 70. Se trata de un teatro, como recuerda en su dossier <A href=\"http:\/\/www.ricardosilvaromero.com\/htmls\/taller\/ensayos\/poesia.htm\">Ricardo Silva Romero<\/a>, de escasa acci\u00f3n y clara influencia del teatro del absurdo: &#8220;El argumento se reduce a una pareja de personajes que dialoga, entre comillas, sobre absolutamente nada. Sobre todo en dos, <em>Laurel and Hardy go to Heaven<\/em> y <em>Hide and Seek<\/em>, no aparece un relato claro. Influido por el teatro del absurdo, Auster se dedica a presentar una realidad en la que no sucede nada. O, mejor, una realidad en la que lo que sucede es que nada sucede&#8221;, apunta. Dossena, que ha confiado la representaci\u00f3n a los actores Alcira Serna y Daniel Toppino, describe as\u00ed la sinopsis de la obra, cuyo t\u00edtulo se ha traducido como &#8216;Espacio Escondido&#8217;.<\/p>\n<blockquote><p><em>&#8220;Una pareja de actores, que vivieron anta\u00f1o la gloria en los escenarios,<br \/>\ndeciden buscar desde su oficio un sentido a sus vidas, encerr\u00e1ndose cada uno en<br \/>\nun \u201cteatrito peque\u00f1o\u201d. Casi parafraseando a las exposiciones, se exhibir\u00e1n como<br \/>\ncuriosidad de una especie en extinci\u00f3n. Presos del marco f\u00edsico que<br \/>\nlos contiene intentaran volver a \u201cbrillar\u201d como en aquellos<br \/>\ntiempos&#8230;<br \/>\nEn el transcurso de esta representaci\u00f3n, se develar\u00e1 su vida<br \/>\nprivada: historia, intimidades, recelos, viejos resquemores y su relaci\u00f3n de<br \/>\npareja. Recordaran una y mil veces sus \u00e9xitos sobre las tablas, as\u00ed como<br \/>\nsus miserias y angustias. Esta met\u00e1fora de la b\u00fasqueda del sentido de la vida,<br \/>\ncon otro y a la vez inexorablemente personal, nos retrotrae a los diversos<br \/>\ncaminos del hombre en pos de su propia realizaci\u00f3n y sentido&#8221;.<\/em><\/p>\n<\/blockquote>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El director teatral argentino Mariano Dossena nos escribe para comunicarnos el estreno, el pr\u00f3ximo 4 de agosto en Buenos Aires (sala La Tertulia), de la adaptaci\u00f3n que ha realizado de la obra de Paul Auster Hide and Seek, uno de los textos teatrales escritos por el neoyorquino en los a\u00f1os 70. Se trata de un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-538","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=538"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/538\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}