{"id":482,"date":"2006-11-18T06:27:00","date_gmt":"2006-11-18T06:27:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=482"},"modified":"2006-11-18T06:27:00","modified_gmt":"2006-11-18T06:27:00","slug":"especial-murakami","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/11\/18\/especial-murakami\/","title":{"rendered":"Especial Murakami"},"content":{"rendered":"<p><A href=\"http:\/\/photos1.blogger.com\/blogger\/6859\/954\/1600\/portada-R.jpg\"><IMG style=\"margin: 0px 10px 10px 0px; float: left;\" alt=\"\" src=\"\/\/photos1.blogger.com\/blogger\/6859\/954\/320\/portada-R.jpg\" border=\"0\"><\/a>La revista espa\u00f1ola <A href=\"http:\/\/www.elcultural.es\/HTML\/20061116\/LETRAS\/LETRAS19071.asp\">El Cultural <\/a>dedica esta semana portada y atenci\u00f3n preferente al lanzamiento de <A href=\"http:\/\/paulauster.blogspot.com\/2006\/11\/lanzamiento-de-kafka-en-la-orilla-de.html\">Kafka en la orilla<\/a>, la \u00faltima novela de Haruki Murakami traducida al castellano, que acaba de publicar la editorial Tusquets. M\u00e1s abajo reproducimos un <A href=\"http:\/\/paulauster.blogspot.com\/2006\/11\/kafka-en-la-orilla-fragmento.html\">fragmento<\/a>.<br \/>\nEl Cultural abunda en la extra\u00f1a personalidad del escritor japon\u00e9s, esquivo a las entrevistas y aficionado a correr diez kil\u00f3metros diarios de buena ma\u00f1ana y a competir en maratones por todo el mundo de forma m\u00e1s o menos an\u00f3nima. Respecto a la novela, la periodita la resume as\u00ed: <em>&#8220;Es misterio, sexo, aventura, dolor, sue\u00f1os, fantasmas, imposible amor. Puro Murakami&#8221;<\/em>.<br \/>\nEn los p\u00e1rrafos siguientes, rescata declaraciones del autor acerca de las claves del relato, el pretendido complejo de Edipo presente en la narraci\u00f3n y otras curiosidades. <em>&#8220;\u2013El mito de Edipo \u2013explica Murakami\u2013 es s\u00f3lo uno de los temas de la novela, y no necesariamente el elemento central. Desde el principio plane\u00e9 escribir sobre un quincea\u00f1ero que huye de su siniestro padre y comienza un viaje en busca de su madre, lo que naturalmente tiene mucho que ver con el mito de Edipo. Pero, como le dec\u00eda, yo no ten\u00eda ese mito en la cabeza desde el principio, aunque los mitos est\u00e9n en el origen de todas las historias. Cuando escribimos un relato no podemos evitar que est\u00e9 relacionado con toda clase de mitos, que son una suerte de dep\u00f3sito en el que est\u00e1n todas las historias<\/em>&#8220;.<br \/>\nEl Cultural adorna el despliegue con <A href=\"http:\/\/www.elcultural.es\/HTML\/20061116\/LETRAS\/LETRAS19072.asp\">esta cr\u00edtica <\/a>de la novela. Arranca as\u00ed: &#8220;<em>Leer una obra de Haruki Murakami (Kyoto, 1949) constituye una verdadera experiencia: sus textos est\u00e1n escritos con la lengua de un dise\u00f1ador verbal. Sus cortes l\u00e9xicos sorprenden por lo modernos, captan el pulso digital y comercial del presente, lleno de marcas, relojes Casio y Rolex, coches BMW y Toyota, las pegatinas del imaginario de la sociedad del bienestar. A la vez, sus personajes existen en un mundo caracterizado por su inestabilidad psicol\u00f3gica; unas veces viven traumatizados por asuntos personales, mientras en ocasiones experimentan circunstancias paranormales, provenientes de un entorno donde ocurren cosas extra\u00f1as. Estos seres de ficci\u00f3n no se hacen a s\u00ed mismos; la casualidad y el impulso gu\u00edan su conducta, configurando una personalidad parad\u00f3jica&#8221;<\/em> <A href=\"http:\/\/www.elcultural.es\/HTML\/20061116\/LETRAS\/LETRAS19072.asp\">(m\u00e1s).<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La revista espa\u00f1ola El Cultural dedica esta semana portada y atenci\u00f3n preferente al lanzamiento de Kafka en la orilla, la \u00faltima novela de Haruki Murakami traducida al castellano, que acaba de publicar la editorial Tusquets. M\u00e1s abajo reproducimos un fragmento. El Cultural abunda en la extra\u00f1a personalidad del escritor japon\u00e9s, esquivo a las entrevistas y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-482","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=482"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/482\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}