{"id":431,"date":"2005-09-28T03:14:00","date_gmt":"2005-09-28T03:14:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=431"},"modified":"2005-09-28T03:14:00","modified_gmt":"2005-09-28T03:14:00","slug":"abc-estrena-blogs","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2005\/09\/28\/abc-estrena-blogs\/","title":{"rendered":"ABC estrena blogs"},"content":{"rendered":"<p> El diario madrile\u00f1o <A href=\"http:\/\/www.abc.es\/\">ABC <\/a>estrena <A href=\"http:\/\/blogs.abc.es\/\">blogs<\/a>. De momento son seis sobre temas gen\u00e9ricos como deportes, cine, televisi\u00f3n, m\u00fasica, gastronom\u00eda y nuevas tecnolog\u00edas. La apuesta del diario cabecera de Vocento ha sido involucrar a sus redactores en la emisi\u00f3n frecuente de ideas a la Red en lugar de abrir el espacio bloguero directamente a los lectores, como hizo <A href=\"http:\/\/blogs.diariovasco.com\/\">El Diario Vasco<\/a>. Los lectores podr\u00e1n participar a trav\u00e9s de los comentarios a los asuntos que vayan publicando los redactores.<br \/>\nLos blogs se estrenan con <A href=\"http:\/\/blogs.abc.es\/elfutbolin\">El Futbol\u00edn<\/a>, l\u00f3gicamente de deportes, con Jos\u00e9 Manuel Cuellar; <A href=\"http:\/\/blogs.abc.es\/unadepiratas\">Una de Piratas<\/a>, de cine, a cargo de Oti Rodr\u00edguez Marchante; <A href=\"http:\/\/blogs.abc.es\/enciendeyvamonos\">Enciende y v\u00e1monos<\/a>, de televisi\u00f3n, por Rosa Belmonte; <A href=\"http:\/\/blogs.abc.es\/LaTostadora\">La Tostadora<\/a>, diario musical por Jos\u00e9 Manuel Costa; <A href=\"http:\/\/blogs.abc.es\/gastronomia\">Salsa de chiles<\/a>, la gastronom\u00eda por Carlos Maribona; y <A href=\"http:\/\/blogs.abc.es\/vidadigital\">Vida Digital<\/a>, dedicado a las nuevas tecnolog\u00edas, por Juan Varela, quien tambi\u00e9n se hace cargo del exitiso e imprescindible <A href=\"http:\/\/www.periodistas21.blogspot.com\/\">Periodistas21.<\/a><br \/>\n<A href=\"http:\/\/www.elcorreo.com\/alava\/edicion\/portada.html\">El Correo<\/a> tiene intenci\u00f3n de poner en marcha en breve una iniciativa similar a la de ABC.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El diario madrile\u00f1o ABC estrena blogs. De momento son seis sobre temas gen\u00e9ricos como deportes, cine, televisi\u00f3n, m\u00fasica, gastronom\u00eda y nuevas tecnolog\u00edas. La apuesta del diario cabecera de Vocento ha sido involucrar a sus redactores en la emisi\u00f3n frecuente de ideas a la Red en lugar de abrir el espacio bloguero directamente a los lectores, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-431","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=431"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/431\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}