{"id":426,"date":"2005-10-04T03:01:00","date_gmt":"2005-10-04T03:01:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=426"},"modified":"2005-10-04T03:01:00","modified_gmt":"2005-10-04T03:01:00","slug":"mas-novedades-ryan-adams","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2005\/10\/04\/mas-novedades-ryan-adams\/","title":{"rendered":"M\u00e1s novedades: Ryan Adams"},"content":{"rendered":"<p>Siguen las novedades discogr\u00e1ficas de oto\u00f1o. Ryan Adams es un t\u00edo prol\u00edfico. O m\u00e1s bien, un autoconsiderado genio que piensa que todo lo que compone tiene calidad para ser grabado. Y a veces, con raz\u00f3n. <A href=\"http:\/\/www.amazon.com\/exec\/obidos\/tg\/detail\/-\/B000AOF9RU\/qid=1128377515\/sr=8-1\/ref=pd_bbs_1\/102-7003477-7152169?v=glance&#038;s=music&#038;n=507846\">Jacksonville City Nights<\/a> es el segundo de los tres \u00e1lbumes que Adams ten\u00eda previsto publicar en 2005. El primero fue Cold Roses, editado en mayo, que cosech\u00f3 buenas cr\u00edticas. Ahora, Adams (ex Whiskeytown, una banda a reivindicar) se atreve con melod\u00edas m\u00e1s country. El pr\u00f3ximo llevar\u00e1 por t\u00edtulo <em>29<\/em> y, a juzgar por los foros de sus fans, se publicar\u00e1 a principios de noviembre con nueve canciones de nueve minutos cada una en formato ac\u00fastico.<br \/>\n<em>Jacksonville<\/em> contiene 14 temas full-band grabados junto a The Cardinals y producidos por Tom Schick. En <em>Dear John<\/em><strong>,<\/strong> Adams canta en dueto junto a Norah Jones.<br \/>\nY atentos a los bonus de la versi\u00f3n inglesa: Adams revisa un cl\u00e1sico como <A href=\"http:\/\/www.ryanadamsonline.com\/music\/62\/565\/\">Always on my mind<\/a>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Siguen las novedades discogr\u00e1ficas de oto\u00f1o. Ryan Adams es un t\u00edo prol\u00edfico. O m\u00e1s bien, un autoconsiderado genio que piensa que todo lo que compone tiene calidad para ser grabado. Y a veces, con raz\u00f3n. Jacksonville City Nights es el segundo de los tres \u00e1lbumes que Adams ten\u00eda previsto publicar en 2005. El primero fue [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-426","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=426"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/426\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}