{"id":418,"date":"2005-09-16T02:46:00","date_gmt":"2005-09-16T02:46:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=418"},"modified":"2005-09-16T02:46:00","modified_gmt":"2005-09-16T02:46:00","slug":"rebelion-los-jurados","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2005\/09\/16\/rebelion-los-jurados\/","title":{"rendered":"Rebeli\u00f3n de los jurados"},"content":{"rendered":"<p>La escritora Maria de la Pau Janer (Palma de Mallorca, 1966), reciente ganadora del Planeta, no es la \u00fanica que ha sufrido la &#8216;rebeli\u00f3n de los jurados&#8217;. Janer, que ya fue finalista del mismo galard\u00f3n en 2002, ha triunfado en una edici\u00f3n ya descafeinada de antemano por miembros del jurado, como Juan Mars\u00e9, que se encarg\u00f3 de anunciar la baja calidad literaria de los ejemplares a concurso en la 54 edici\u00f3n del premio mejor dotado de la literatura espa\u00f1ola.<br \/>\nPero no es un caso aislado. Ocurri\u00f3 lo mismo en el premio Torrevieja de novela, \u00e9sta vez con el autor C\u00e9sar Vidal de ganador cuestionado y con Jos\u00e9 Manuel Caballero Bonald como jurado rebelde. <\/p>\n<p>Los libros:<br \/>\nMar\u00eda de la Pau Janer: &#8216;Pasiones romanas&#8217;<br \/>\nJaime Bayly (finalista): &#8216;Y de repente, un \u00e1ngel&#8217;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La escritora Maria de la Pau Janer (Palma de Mallorca, 1966), reciente ganadora del Planeta, no es la \u00fanica que ha sufrido la &#8216;rebeli\u00f3n de los jurados&#8217;. Janer, que ya fue finalista del mismo galard\u00f3n en 2002, ha triunfado en una edici\u00f3n ya descafeinada de antemano por miembros del jurado, como Juan Mars\u00e9, que se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-418","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}