{"id":392,"date":"2005-12-05T02:50:00","date_gmt":"2005-12-05T02:50:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=392"},"modified":"2005-12-05T02:50:00","modified_gmt":"2005-12-05T02:50:00","slug":"rain-taxi-subasta-ediciones-firmadas-auster","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2005\/12\/05\/rain-taxi-subasta-ediciones-firmadas-auster\/","title":{"rendered":"Rain Taxi subasta ediciones firmadas de Auster"},"content":{"rendered":"<p>       La revista de cr\u00edtica literaria <A href=\"http:\/\/www.raintaxi.com\/\">Rain Taxi<\/a>, radicada en Minneapolis (Minnesotta, EE UU), una <A href=\"http:\/\/www.startribune.com\/stories\/384\/5759653.html\">referencia en la materia<\/a> en el norte de los Estados Unidos, celebra este oto\u00f1o su d\u00e9cimo aniversario con una nueva edici\u00f3n de la publicaci\u00f3n (tiene una tirada de 18.000 ejemplares, la mayor\u00eda por <A href=\"http:\/\/www.raintaxi.com\/subscribers\/\">suscripci\u00f3n<\/a>) y con una subasta de objetos curiosos. Entre ellos, primeras ediciones de Auster y libros firmados por el autor neoyorquino.<br \/>\nLa subasta est\u00e1 en Ebay y entre otras cosas hemos encontrado:<br \/>\nUna <A href=\"http:\/\/cgi.ebay.com\/Paul-Auster-Rain-Taxi-SIGNED-CHAPBOOK-Surrealist-Poem_W0QQitemZ6586052006QQcategoryZ29223QQrdZ1QQcmdZViewItem#ebayphotohosting\">antolog\u00eda de poemas<\/a> surrealistas dirigida por Auster en 1972, ya descatalogada. Firmada por el autor. $75.<br \/>\nPrimera edici\u00f3n de <A href=\"http:\/\/cgi.ebay.com\/Paul-Auster-SIGNED-ADVANCE-RDING-COPY-Book-of-Illusion_W0QQitemZ8360607854QQcategoryZ377QQrdZ1QQcmdZViewItem\">El Libro de las Ilusiones<\/a>, 2002, firmada. $15.<br \/>\nPero hay m\u00e1s.<br \/>\nVersi\u00f3n gr\u00e1fica de <A href=\"http:\/\/cgi.ebay.com\/Paul-Auster-SIGNED-City-of-Glass_W0QQitemZ8360236827QQcategoryZ377QQssPageNameZWDVWQQrdZ1QQcmdZViewItem\">City of Glass<\/a>, primera edici\u00f3n brit\u00e1nica, Faber&#038;Faber 2005. $10.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La revista de cr\u00edtica literaria Rain Taxi, radicada en Minneapolis (Minnesotta, EE UU), una referencia en la materia en el norte de los Estados Unidos, celebra este oto\u00f1o su d\u00e9cimo aniversario con una nueva edici\u00f3n de la publicaci\u00f3n (tiene una tirada de 18.000 ejemplares, la mayor\u00eda por suscripci\u00f3n) y con una subasta de objetos curiosos. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-392","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=392"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/392\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}