{"id":382,"date":"2005-12-17T02:25:00","date_gmt":"2005-12-17T02:25:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=382"},"modified":"2005-12-17T02:25:00","modified_gmt":"2005-12-17T02:25:00","slug":"the-brooklyn-follies-punto-ee-uu","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2005\/12\/17\/the-brooklyn-follies-punto-ee-uu\/","title":{"rendered":"The Brooklyn Follies, a punto en EE UU"},"content":{"rendered":"<p><A href=\"http:\/\/photos1.blogger.com\/blogger\/6859\/954\/1600\/0805077146.01._SCLZZZZZZZ_.jpg\"><IMG style=\"margin: 0px 10px 10px 0px; float: left; width: 131px; height: 181px;\" alt=\"\" src=\"\/\/photos1.blogger.com\/blogger\/6859\/954\/320\/0805077146.01._SCLZZZZZZZ_.jpg\" border=\"0\" height=\"245\" width=\"178\"><\/a><br \/>\nThe Brooklyn Follies, la m\u00e1s reciente novela de Paul Auster, estar\u00e1 por fin disponible en Estados Unidos en apenas diez d\u00edas. Se anuncia para el <A href=\"http:\/\/www.amazon.com\/gp\/product\/0805077146\/qid=1134811910\/sr=8-1\/ref=pd_bbs_1\/104-3895875-3775923?n=507846&#038;s=books&#038;v=glance\">27 de diciembre<\/a>, aunque ya comienzan a aparecer las cr\u00edticas literarias en las publicaciones americanas, prueba de que ya circulan copias en el sector. Hoy publica una <A href=\"http:\/\/www.villagevoice.com\/books\/0551,stosuy,71103,10.html\">The Village Voice<\/a>, una de las tradicionales revistas de Nueva York. La novela se ha venido publicando desde el verano en los diferentes pa\u00edses europeos (menos Espa\u00f1a, donde llegar\u00e1 en enero o febrero, seg\u00fan <A href=\"http:\/\/www.anagrama-ed.es\/\">Anagrama<\/a>) y es curioso que la misma edici\u00f3n anglosajona se haya editado meses antes en Inglaterra o Australia que en los USA.<br \/>\n<A href=\"http:\/\/paulauster.blogspot.com\/2005\/11\/gua-de-comentarios-sobre-brooklyn.html\">Esto es Brooklyn | Gu\u00eda de comentarios<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>The Brooklyn Follies, la m\u00e1s reciente novela de Paul Auster, estar\u00e1 por fin disponible en Estados Unidos en apenas diez d\u00edas. Se anuncia para el 27 de diciembre, aunque ya comienzan a aparecer las cr\u00edticas literarias en las publicaciones americanas, prueba de que ya circulan copias en el sector. Hoy publica una The Village Voice, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-382","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=382"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/382\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}