{"id":325,"date":"2007-02-27T02:21:00","date_gmt":"2007-02-27T02:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=325"},"modified":"2007-02-27T02:21:00","modified_gmt":"2007-02-27T02:21:00","slug":"nativel-preciado","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/02\/27\/nativel-preciado\/","title":{"rendered":"Nativel Preciado"},"content":{"rendered":"<p> La escritora y periodista <A href=\"http:\/\/www.escritoras.com\/escritoras\/escritora.php?i=-903429710\">Nativel Preciado <\/a>ha ganado la und\u00e9cima edici\u00f3n del <A href=\"http:\/\/www.epdlp.com\/premios.php?premio=Primavera\">Premio Primavera de Novela<\/a> con la novela &#8220;Olvida el Para\u00edso&#8221;, una obra que reflexiona sobre &#8220;la superaci\u00f3n del dolor que suponen el desamor y la muerte&#8221;, seg\u00fan describi\u00f3 la autora poco despu\u00e9s de conocer el fallo. Por otra parte, la escritora catalana Care Santos, que hasta ahora se hab\u00eda dedicado a la literatura juvenil, qued\u00f3 finalista de este premio con la obra &#8220;La muerte de Venus&#8221;, seg\u00fan dio a conocer hoy en el C\u00edrculo de Bellas Artes el jurado del certamen, convocado conjuntamente por la promotora \u00c1mbito Cultural y la editorial Espasa.<br \/>\n[V\u00eda <A href=\"http:\/\/www.abc.es\/20070227\/cultura-libros\/nativel-preciado-gana-premio_200702271324.html\">ABC.es<\/a>, sobre teletipo de Efe]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La escritora y periodista Nativel Preciado ha ganado la und\u00e9cima edici\u00f3n del Premio Primavera de Novela con la novela &#8220;Olvida el Para\u00edso&#8221;, una obra que reflexiona sobre &#8220;la superaci\u00f3n del dolor que suponen el desamor y la muerte&#8221;, seg\u00fan describi\u00f3 la autora poco despu\u00e9s de conocer el fallo. Por otra parte, la escritora catalana Care [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-325","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=325"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/325\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}