{"id":317,"date":"2006-11-26T06:21:00","date_gmt":"2006-11-26T06:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=317"},"modified":"2006-11-26T06:21:00","modified_gmt":"2006-11-26T06:21:00","slug":"nuevas-criticas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2006\/11\/26\/nuevas-criticas\/","title":{"rendered":"Nuevas cr\u00edticas"},"content":{"rendered":"<p><A href=\"http:\/\/paulauster.blogspot.com\/2006\/10\/gua-de-crticas-sobre-travels-in_12.html\">Travels in the Scriptorium<\/a>, la \u00faltima novela de Paul Auster, ha aparecido ya en los mercados anglosajones del pac\u00edfico, Australia y Nueva Zelanda. Antes a\u00fan, por tanto, que en el pa\u00eds natal de Auster, donde Henry Holt espera publicar el publicar el libro a comienzos de 2007. A\u00f1adimos a nuestra <A href=\"http:\/\/paulauster.blogspot.com\/2006\/10\/gua-de-crticas-sobre-travels-in_12.html\">Gu\u00eda de Cr\u00edticas<\/a>, por tanto, algunos comentarios aparecidos en los principales peri\u00f3dicos de la zona, como <A href=\"http:\/\/www.theaustralian.news.com.au\/story\/0,20867,20717423-5003900,00.html\">The Australian <\/a>o<A href=\"http:\/\/www.nzherald.co.nz\/category\/story.cfm?c_id=18&#038;objectid=10351583\"> The New Zealand Herald<\/a>. Yo ya he le\u00eddo tambi\u00e9n mi copia de Travels. Y bueno, como vienen a rese\u00f1ar la mayor\u00eda de las cr\u00edticas, se trata de un interesante ejercicio de metaliteratura, un curioso relato menor que elude la narraci\u00f3n de una historia (al menos en primer plano; Auster vuelve a jugar con cajas chinas) para centrarse en el relato psicol\u00f3gico sin resoluci\u00f3n clara. Lo bueno, que los fans de Auster recordar\u00e1n a medida que lean la novela a los personajes de libros anteriores (Anna Blume, Fanshawe, Quinn&#8230;) que regresan ante quien parece el alter-ego del escritor, Mr. Blank, un anciano encerrado en una habitaci\u00f3n. Lo malo, que los nuevos lectores del neoyorquino, que en el mundo de habla hispana posiblemente se acerquen a la novela tras el revuelo medi\u00e1tico que caus\u00f3 su obtenci\u00f3n del <A href=\"http:\/\/paulauster.blogspot.com\/2006\/10\/auster-y-almodovar-unidos-por-las.html\">Pr\u00edncipe de Asturias<\/a>, se encontrar\u00e1n con un relato para iniciados, poco representativo de la literatura de Auster.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Travels in the Scriptorium, la \u00faltima novela de Paul Auster, ha aparecido ya en los mercados anglosajones del pac\u00edfico, Australia y Nueva Zelanda. Antes a\u00fan, por tanto, que en el pa\u00eds natal de Auster, donde Henry Holt espera publicar el publicar el libro a comienzos de 2007. A\u00f1adimos a nuestra Gu\u00eda de Cr\u00edticas, por tanto, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-317","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/317\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}