{"id":305,"date":"2007-02-27T02:01:00","date_gmt":"2007-02-27T02:01:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=305"},"modified":"2007-02-27T02:01:00","modified_gmt":"2007-02-27T02:01:00","slug":"carlos-perez-uralde","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/02\/27\/carlos-perez-uralde\/","title":{"rendered":"Carlos P\u00e9rez Uralde"},"content":{"rendered":"<p><span style=\"font-style: italic;\">No te amo tristemente, como los vencidos.<\/span><br \/>\n<span style=\"font-style: italic;\">Puedes o\u00edrme cantar cuando el tiempo se hace niebla<\/span><br \/>\n<span style=\"font-style: italic;\">cuando la lluvia dibuja agujas en la calle<\/span><br \/>\n<span style=\"font-style: italic;\">y el rostro de los hombres se hace duro<\/span><br \/>\n<span style=\"font-style: italic;\">y las casas y los perros trituran esperanzas<\/span><br \/>\n<span style=\"font-style: italic;\">en el suelo. Existe en m\u00ed mucho m\u00e1s<\/span><br \/>\n<span style=\"font-style: italic;\">que los largos desfiles de mujeres despintadas<\/span><br \/>\n<span style=\"font-style: italic;\">con largas venas de agua<\/span><br \/>\n<span style=\"font-style: italic;\">cruzadas al pie de la garganta.<\/span><br \/>\n<span style=\"font-style: italic;\">La calle y los hospitales son selvas de sangre<\/span><br \/>\n<span style=\"font-style: italic;\">y yo estoy creado de deseo y de furia<\/span><br \/>\n<span style=\"font-style: italic;\">y tal vez, quiz\u00e1, de peque\u00f1os granos de arroz<\/span><br \/>\n<span style=\"font-style: italic;\">en las solapas. No te amo tristemente como amar\u00eda<\/span><br \/>\n<span style=\"font-style: italic;\">un vencido.<\/span><br \/>\n<span style=\"font-style: italic;\">Mis manos han ganado todas las batallas.<\/span><\/p>\n<p>La poes\u00eda se titula &#8216;Canci\u00f3n&#8217; y es de Carlos P\u00e9rez Uralde, escritor y cronista vitoriano que desde los a\u00f1os 90 ha reflejado a trav\u00e9s de una columna diaria la vida de su ciudad, Vitoria, en las p\u00e1ginas de <A href=\"http:\/\/www.elcorreo.com\/alava\/\">El Correo<\/a>, mi peri\u00f3dico. Carlos falleci\u00f3 de forma repentina hace un a\u00f1o, dejando una exigua producci\u00f3n de ensayos y cuentos para su enorme val\u00eda literaria y una buena colecci\u00f3n de poemas juveniles, algunos in\u00e9ditos. \u00c9ste es uno de ellos, que ahora han sido publicados por El Correo en una edici\u00f3n especial dise\u00f1ada por el artista Fernando Illana e ilustrada por el pintor I\u00f1aki Cerrajer\u00eda. Sus amigos, compa\u00f1eros y lectores le homenajearon la semana pasada, en una <A href=\"http:\/\/www.elcorreo.com\/alava\/prensa\/20070325\/alava\/ironia-insustituible_20070325.html\">celebraci\u00f3n literaria musical<\/a> (Carlos vivi\u00f3 a trav\u00e9s de las canciones de Dylan, Serrat, Beatles y Springsteen) con motivo del que debiera haber sido su 53 cumplea\u00f1os.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No te amo tristemente, como los vencidos. Puedes o\u00edrme cantar cuando el tiempo se hace niebla cuando la lluvia dibuja agujas en la calle y el rostro de los hombres se hace duro y las casas y los perros trituran esperanzas en el suelo. Existe en m\u00ed mucho m\u00e1s que los largos desfiles de mujeres [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-305","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}