{"id":293,"date":"2007-04-09T01:42:00","date_gmt":"2007-04-09T01:42:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=293"},"modified":"2007-04-09T01:42:00","modified_gmt":"2007-04-09T01:42:00","slug":"lou-reed-expone-milan","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/04\/09\/lou-reed-expone-milan\/","title":{"rendered":"Lou Reed expone en Mil\u00e1n"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp3.blogger.com\/_LSCWnEpAnto\/RhobGqNN2LI\/AAAAAAAAAEg\/CW60xDL-xIQ\/s1600-h\/P_Lou+Reed_NewYork+.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/bp3.blogger.com\/_LSCWnEpAnto\/RhobGqNN2LI\/AAAAAAAAAEg\/CW60xDL-xIQ\/s320\/P_Lou+Reed_NewYork+.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5051379733272320178\" border=\"0\"><\/a>La galer\u00eda <A href=\"http:\/\/www.galleriarteutopia.com\/mostra_in_corso.html\">Arteutopia<\/a> de Mil\u00e1n (Italia) expone el trabajo fotogr\u00e1fico de <A href=\"http:\/\/www.loureed.org\/00\/index.html\">Lou Reed<\/a> recopilado bajo el t\u00edtulo gen\u00e9rico &#8216;Lou Reed&#8217;s New York&#8217;, que ya hemos comentado aqu\u00ed. La muestra estar\u00e1 abierta hasta el 12 de mayo.<\/p>\n<blockquote style=\"font-style: italic;\"><p>Esto es Brooklyn. 4\/5\/06. Lou Reed <A href=\"http:\/\/paulauster.blogspot.com\/2005\/10\/lou-reed-fotografa-nueva-york.html\">lleva a\u00f1<\/a><A href=\"http:\/\/paulauster.blogspot.com\/2005\/10\/lou-reed-fotografa-nueva-york.html\">o<\/a><A href=\"http:\/\/paulauster.blogspot.com\/2005\/10\/lou-reed-fotografa-nueva-york.html\">s<\/a> madrugando para captar la luz de Nueva York, del r\u00edo Hudson y de la evocadora silueta de Manhattan, quiz\u00e1 uno de los espect\u00e1culos urbanos m\u00e1s maravillosos que se pueden contemplar. El <A href=\"http:\/\/paulauster.blogspot.com\/2006\/01\/lou-reed-expone-en-herms.html\">trabajo fotogr\u00e1fico<\/a> de Lou Reed ha viajado a Europa y estos d\u00edas se expone por primera vez en una <A href=\"http:\/\/www.exibart.com\/profilo\/eventiV2.asp\/idelemento\/29485\">galer\u00eda de arte contempor\u00e1neo de Roma<\/a>, Italia, llamada <A href=\"http:\/\/www.unosunove.com\/\">Uno Su Nove<\/a>. La muestra se compone de 55 fotograf\u00edas, todas sin presencia humana en un af\u00e1n de descubrir una ciudad desnuda, sin maquillajes ni artificios. En la exposici\u00f3n, de hecho, el \u00fanico humano presente en las instant\u00e1neas es el propio Reed, autoinmortalizado en un retrato en blanco y negro. &#8220;Me encanta el aspecto de m\u00e1rmol que he conseguido en esa imagen. Parece una escultura&#8221;, dice el neoyorquino. Reed, que concedi\u00f3 una entrevista a <A href=\"http:\/\/www.elmundo.es\/elmundo\/2006\/05\/03\/cultura\/1146650195.html\">El Mundo<\/a> durante la presentaci\u00f3n de la muestra romana, no ve diferencias entre la m\u00fasica y la fotograf\u00eda. &#8220;Para mi es todo lo mismo, son dedos de una misma mano. Si pudiera pintar, lo har\u00eda, pero desgraciadamente no s\u00e9&#8221;. Se desconoce a\u00fan si la exhibici\u00f3n llegar\u00e1 a Espa\u00f1a (<A href=\"http:\/\/www.elpais.es\/articulo\/elpporcul\/20060202elpepucul_4\/Tes\/cultura\/Lou\/Reed\/expone\/vision\/Nueva\/York\">El Pa\u00eds dice que quiz\u00e1 a finales de a\u00f1o<\/a>), pero estaremos al tanto. Para abrir boca, un libro: <A href=\"http:\/\/www.amazon.com\/gp\/product\/3865211526\/qid=1146761904\/sr=2-1\/ref=pd_bbs_b_2_1\/002-3801409-9417664?s=books&#038;v=glance&#038;n=283155\">Lou Reed&#8217;s New York<\/a>.<\/p><\/blockquote>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La galer\u00eda Arteutopia de Mil\u00e1n (Italia) expone el trabajo fotogr\u00e1fico de Lou Reed recopilado bajo el t\u00edtulo gen\u00e9rico &#8216;Lou Reed&#8217;s New York&#8217;, que ya hemos comentado aqu\u00ed. La muestra estar\u00e1 abierta hasta el 12 de mayo. Esto es Brooklyn. 4\/5\/06. Lou Reed lleva a\u00f1os madrugando para captar la luz de Nueva York, del r\u00edo Hudson [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-293","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=293"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/293\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}